{"id":2648,"date":"2018-12-30T16:53:52","date_gmt":"2018-12-30T15:53:52","guid":{"rendered":"https:\/\/wolf-of-seo.de\/?p=2648"},"modified":"2018-12-30T16:53:52","modified_gmt":"2018-12-30T15:53:52","slug":"seo-texts-writing-seo-basics-7","status":"publish","type":"post","link":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/","title":{"rendered":"SEO Text Writing (SEO Basics #7)"},"content":{"rendered":"<p>Die Webtexte, der Content ist das wichtigste auf der Webseite. Eine Webseite ohne Text ist so gut wie gar nicht m&#xF6;glich bei den Suchmaschinen in die Top-10 zu bekommen. Ohne Text und Content ist auch der User meist vollkommen verloren. Ok, es gibt Seiten, wie z.B. von Fotografen, dort sind viele Bilder und man kann kaum Text schreiben, aber auch hier sollte erst Recht dann einmal ein richtig guter Text geschrieben werden, damit die Seite &#xFC;berhaupt Besucher bekommt, und dann muss der verlorene Punkt durch andere <a href=\"https:\/\/wolf-of-seo.de\/leistungen\/\">SEO Ma&#xDF;nahmen<\/a> ausgeglichen werden.<\/p>\n<p>&#xA0;<\/p>\n<h2><strong>SEO Texte und SEO Content schreiben<\/strong><\/h2>\n<p>So, nun aber zur&#xFC;ck zum Thema Text \/ Content. Der Text einer Webseite sollte mindestens 300 Zeichen enthalten. Obwohl das schon ziemlich gering ist. Ich empfehle grunds&#xE4;tzlich 2.000 Zeichen. Auch dann kann man die Keyw&#xF6;rter sinnig einsetzen und evtl. auch ein zweites Keywort im gleichen Text noch unterbringen. Ein Keywort sollte ungef&#xE4;hr eine Dichte von 1-3% haben. Diese Dichte kann man ganz einfach ausrechnen. Z&#xE4;hlt die Keyw&#xF6;rter im Text und multipliziert diese mit 100 danach dividiert durch die Anzahl aller W&#xF6;rter: Anzahl Keyw&#xF6;rter * 100 : Anzahl alle W&#xF6;rter = Keywort Dichte.<\/p>\n<p>Mehr als 3 Prozent sollten nicht genutzt werden, ich habe bislang schlechte Erfahrungen gemacht, bei h&#xF6;heren Werten. Wenn mehr Keyw&#xF6;rter ben&#xF6;tigt werden, k&#xF6;nnen diese im &#x201E;title&#x201C;-Attribut von Bilder und Links gesetzt werden. Was durchaus sehr sinnig ist, dieses <a href=\"https:\/\/wolf-of-seo.de\/blog\/title-tags-seo-tipps\/\">&#x201E;title&#x201C;-Attribut<\/a> grunds&#xE4;tzlich zu nutzen.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>Interne Links erstellen f&#xFC;r Suchmaschinen und Nutzer<\/strong><\/h3>\n<p>Nun sollte Ihr Text noch einige <a href=\"https:\/\/wolf-of-seo.de\/blog\/interne-verlinkung-seo-ranking\/\">Links<\/a> enthalten. Einmal damit der Besucher auf der Seite verweilt und noch andere Texte liest, aber auch wichtig f&#xFC;r die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchmaschine<\/span>. Die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchmaschine<\/span> verkn&#xFC;pft und gewichtet, durch diese Links, den Inhalt der Webseite mit anderen. Auch wichtig ist es Links einzubauen, die auf externe Seiten verweisen. Auch hierdurch wird die Webseite bewertet. Zu viele sind nat&#xFC;rlich wieder nicht gut. Aber 2 bis 3 externe Links sollten versucht werden einzubauen. Interne Links sollten nicht mehr als 10 gesetzt sein. Links im Text sind besser als Links die unter- oder oberhalb des Textes angezeigt werden.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>Ihre SEO Texte sollten &#x201E;Leichte Kost&#x201C; bleiben<\/strong><\/h3>\n<p>Das wichtigste aber noch am Ende, bitte bitte schreibt den Text nicht in &#x201E;Doktorsprache&#x201C;, Texte sollten von jedem verstanden werden! Auch was sehr wichtig ist, bedenkt bei aller M&#xFC;he mit der Suchmaschinenoptimierung, der Text wird von Menschen gelesen und sollte nicht so geschrieben werden, das noch dieses oder jenes <a href=\"https:\/\/wolf-of-seo.de\/blog\/google-keyword-recherche-matrix\/\">Keyword<\/a> irgendwo rein gequetscht wird. Google und Co. Erkennen immer besser ob ein Text &#x201E;lesbar&#x201C; ist oder nicht, geschweige den, der Leser merkt es sofort und verl&#xE4;sst die Seite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Webtexte, der Content ist das wichtigste auf der Webseite. Eine Webseite ohne Text ist so gut wie gar nicht m&#xF6;glich bei den Suchmaschinen in die Top-10 zu bekommen. Ohne Text und Content ist auch der User meist vollkommen verloren. Ok, es gibt Seiten, wie z.B. von Fotografen, dort sind viele Bilder und man kann [&#x2026;]<\/p>\n","protected":false},"author":3,"featured_media":2649,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grundlagen"],"acf":{"dynamic_banner":null,"show_faq":null,"faq_q_1":null,"faq_antwort_1":null,"faq_q_2":null,"faq_antwort_2":null,"faq_q_3":null,"faq_antwort_3":null,"faq_q_4":null,"faq_antwort_4":null,"faq_q_5":null,"faq_antwort_5":null,"faq_q_6":null,"faq_antwort_6":null,"faq_q_7":null,"faq_antwort_7":null,"faq_q_8":null,"faq_antwort_8":null,"faq_q_9":null,"faq_antwort_9":null,"faq_q_10":null,"faq_antwort_10":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SEO Texte schreiben (SEO Grundlagen #7) | WOLF OF SEO<\/title>\n<meta name=\"description\" content=\"Der Content ist das wichtigste auf der Webseite. Eine Webseite ohne SEO Texte ist so gut wie gar nicht bei den Suchmaschinen in die Top-10 zu bekommen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEO Texte schreiben (SEO Grundlagen #7)\" \/>\n<meta property=\"og:description\" content=\"Der Content ist das wichtigste auf der Webseite. Eine Webseite ohne SEO Texte ist so gut wie gar nicht bei den Suchmaschinen in die Top-10 zu bekommen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/\" \/>\n<meta property=\"og:site_name\" content=\"WOLF OF SEO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wolf.of.seo.ns\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/n.sniprs\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-30T15:53:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/text-editor-1794110_1280.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Niels Stuck\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wolf_of_seo\" \/>\n<meta name=\"twitter:site\" content=\"@wolf_of_seo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Niels Stuck\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/\"},\"author\":{\"name\":\"Niels Stuck\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/person\\\/013374d61ad2b66997fc16e2807fbbf7\"},\"headline\":\"SEO Texte schreiben (SEO Grundlagen #7)\",\"datePublished\":\"2018-12-30T15:53:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/\"},\"wordCount\":442,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/text-editor-1794110_1280.png\",\"articleSection\":[\"SEO Grundlagen\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/\",\"name\":\"SEO Texte schreiben (SEO Grundlagen #7) | WOLF OF SEO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/text-editor-1794110_1280.png\",\"datePublished\":\"2018-12-30T15:53:52+00:00\",\"description\":\"Der Content ist das wichtigste auf der Webseite. Eine Webseite ohne SEO Texte ist so gut wie gar nicht bei den Suchmaschinen in die Top-10 zu bekommen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/text-editor-1794110_1280.png\",\"contentUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/text-editor-1794110_1280.png\",\"caption\":\"SEO Texte schreiben\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/seo-texts-writing-seo-basics-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wolf-of-seo.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEO Texte schreiben (SEO Grundlagen #7)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#website\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/\",\"name\":\"WOLF OF SEO\",\"description\":\"Die E-Commerce SEO-Agentur\",\"publisher\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wolf-of-seo.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\",\"name\":\"WOLF OF SEO\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo_wos_beitragsbild3.jpg\",\"contentUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo_wos_beitragsbild3.jpg\",\"width\":1,\"height\":1,\"caption\":\"WOLF OF SEO\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wolf.of.seo.ns\",\"https:\\\/\\\/x.com\\\/wolf_of_seo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/person\\\/013374d61ad2b66997fc16e2807fbbf7\",\"name\":\"Niels Stuck\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9598d9b5cbe93cca9b08868beffeacf059426ba087d49d1eda3bbc9498e467aa?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9598d9b5cbe93cca9b08868beffeacf059426ba087d49d1eda3bbc9498e467aa?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9598d9b5cbe93cca9b08868beffeacf059426ba087d49d1eda3bbc9498e467aa?s=96&d=blank&r=g\",\"caption\":\"Niels Stuck\"},\"description\":\"Niels Stuck hat 10 Jahre SEO Erfahrung und ist Gr\u00fcnder der SEO Agentur \u201cWOLF OF SEO\u201d. Durch dem Aufbau von 20+ Affiliate-Seiten sammelte neben seinem Marketingstudium Praxiserfahrung. Abschlie\u00dfend schrieb er seine Bachelorarbeit \u00fcber den Einfluss von SEO auf Google Rankings, Traffic und Umsatzentwicklung in Form einer Case Study. Heute ist er spezialisiert auf E-Commerce-SEO und hilft mehr als 80 Unternehmen durch SEO einen nachhaltigen organischen Umsatzkanal aufzubauen. Niels ber\u00e4t Startups, etablierte Marken und Konzerne in der Suchmaschinenoptimierung Ihrer Onlineshops und setzt prim\u00e4r auf datenbasierte Contentstrategien und Linkbuilding. Sein Wissen \u00fcber SEO und Onlinemarketing teilt er in diesem Blog, als Speaker auf Konferenzen, in Podcasts und als Gastautor f\u00fcr OMT, Forbes, Starting Up und vielen weiteren Plattformen.\",\"sameAs\":[\"https:\\\/\\\/wolf-of-seo.de\\\/team-uebersicht\\\/niels-stuck\\\/\",\"https:\\\/\\\/www.facebook.com\\\/n.sniprs\\\/\",\"https:\\\/\\\/www.instagram.com\\\/nielsstuck.de\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/niels-stuck-082167113\\\/\",\"https:\\\/\\\/x.com\\\/wolf_of_seo\"],\"honorificSuffix\":\"B.Sc\",\"birthDate\":\"1995-10-22\",\"gender\":\"m\u00e4nnlich\",\"knowsAbout\":[\"SEO\",\"Onlinemarketing\",\"SEA\",\"Suchmachinenoptimierung\",\"Linkbuilding\",\"Contentmarketing\"],\"knowsLanguage\":[\"Deutsch\",\"Englisch\"],\"jobTitle\":\"CEO\",\"worksFor\":\"WOLF OF SEO FZ LLC\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Writing SEO Texts (SEO Basics #7) | WOLF OF SEO","description":"The content is the most important thing on the website. A website without SEO texts is almost impossible to get into the top 10 of search engines.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/","og_locale":"en_US","og_type":"article","og_title":"SEO Texte schreiben (SEO Grundlagen #7)","og_description":"Der Content ist das wichtigste auf der Webseite. Eine Webseite ohne SEO Texte ist so gut wie gar nicht bei den Suchmaschinen in die Top-10 zu bekommen.","og_url":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/","og_site_name":"WOLF OF SEO","article_publisher":"https:\/\/www.facebook.com\/wolf.of.seo.ns","article_author":"https:\/\/www.facebook.com\/n.sniprs\/","article_published_time":"2018-12-30T15:53:52+00:00","og_image":[{"url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/text-editor-1794110_1280.png","width":1,"height":1,"type":"image\/png"}],"author":"Niels Stuck","twitter_card":"summary_large_image","twitter_creator":"@wolf_of_seo","twitter_site":"@wolf_of_seo","twitter_misc":{"Written by":"Niels Stuck","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/#article","isPartOf":{"@id":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/"},"author":{"name":"Niels Stuck","@id":"https:\/\/wolf-of-seo.de\/#\/schema\/person\/013374d61ad2b66997fc16e2807fbbf7"},"headline":"SEO Texte schreiben (SEO Grundlagen #7)","datePublished":"2018-12-30T15:53:52+00:00","mainEntityOfPage":{"@id":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/"},"wordCount":442,"commentCount":0,"publisher":{"@id":"https:\/\/wolf-of-seo.de\/#organization"},"image":{"@id":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/#primaryimage"},"thumbnailUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/text-editor-1794110_1280.png","articleSection":["SEO Grundlagen"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/","url":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/","name":"Writing SEO Texts (SEO Basics #7) | WOLF OF SEO","isPartOf":{"@id":"https:\/\/wolf-of-seo.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/#primaryimage"},"image":{"@id":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/#primaryimage"},"thumbnailUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/text-editor-1794110_1280.png","datePublished":"2018-12-30T15:53:52+00:00","description":"The content is the most important thing on the website. A website without SEO texts is almost impossible to get into the top 10 of search engines.","breadcrumb":{"@id":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/#primaryimage","url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/text-editor-1794110_1280.png","contentUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/text-editor-1794110_1280.png","caption":"SEO Texte schreiben"},{"@type":"BreadcrumbList","@id":"https:\/\/wolf-of-seo.de\/en\/blog\/seo-texts-writing-seo-basics-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wolf-of-seo.de\/"},{"@type":"ListItem","position":2,"name":"SEO Texte schreiben (SEO Grundlagen #7)"}]},{"@type":"WebSite","@id":"https:\/\/wolf-of-seo.de\/#website","url":"https:\/\/wolf-of-seo.de\/","name":"WOLF OF SEO","description":"The e-commerce SEO agency","publisher":{"@id":"https:\/\/wolf-of-seo.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wolf-of-seo.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wolf-of-seo.de\/#organization","name":"WOLF OF SEO","url":"https:\/\/wolf-of-seo.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wolf-of-seo.de\/#\/schema\/logo\/image\/","url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2021\/11\/logo_wos_beitragsbild3.jpg","contentUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2021\/11\/logo_wos_beitragsbild3.jpg","width":1,"height":1,"caption":"WOLF OF SEO"},"image":{"@id":"https:\/\/wolf-of-seo.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wolf.of.seo.ns","https:\/\/x.com\/wolf_of_seo"]},{"@type":"Person","@id":"https:\/\/wolf-of-seo.de\/#\/schema\/person\/013374d61ad2b66997fc16e2807fbbf7","name":"Niels Stuck","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9598d9b5cbe93cca9b08868beffeacf059426ba087d49d1eda3bbc9498e467aa?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9598d9b5cbe93cca9b08868beffeacf059426ba087d49d1eda3bbc9498e467aa?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9598d9b5cbe93cca9b08868beffeacf059426ba087d49d1eda3bbc9498e467aa?s=96&d=blank&r=g","caption":"Niels Stuck"},"description":"Niels Stuck has 10 years of SEO experience and is the founder of the SEO agency \"WOLF OF SEO\". He gained practical experience by building 20+ affiliate sites alongside his marketing studies. Finally, he wrote his bachelor thesis about the influence of SEO on Google rankings, traffic and sales development in the form of a case study. Today, he specializes in e-commerce SEO and helps more than 80 companies build a sustainable organic revenue channel through SEO. Niels advises startups, established brands and corporations in search engine optimization of their online stores and primarily focuses on data-based content strategies and link building. He shares his knowledge about SEO and online marketing in this blog, as a speaker at conferences, in podcasts and as a guest author for OMT, Forbes, Starting Up and many more platforms.","sameAs":["https:\/\/wolf-of-seo.de\/team-uebersicht\/niels-stuck\/","https:\/\/www.facebook.com\/n.sniprs\/","https:\/\/www.instagram.com\/nielsstuck.de\/","https:\/\/www.linkedin.com\/in\/niels-stuck-082167113\/","https:\/\/x.com\/wolf_of_seo"],"honorificSuffix":"B.Sc","birthDate":"1995-10-22","gender":"m\u00e4nnlich","knowsAbout":["SEO","Onlinemarketing","SEA","Suchmachinenoptimierung","Linkbuilding","Contentmarketing"],"knowsLanguage":["Deutsch","Englisch"],"jobTitle":"CEO","worksFor":"WOLF OF SEO FZ LLC"}]}},"_links":{"self":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/posts\/2648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/comments?post=2648"}],"version-history":[{"count":0,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/posts\/2648\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/media\/2649"}],"wp:attachment":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/media?parent=2648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/categories?post=2648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/tags?post=2648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}