{"id":2577,"date":"2019-01-06T00:57:54","date_gmt":"2019-01-05T23:57:54","guid":{"rendered":"https:\/\/wolf-of-seo.de\/?p=2577"},"modified":"2021-12-21T18:37:46","modified_gmt":"2021-12-21T17:37:46","slug":"google-search-console-features","status":"publish","type":"post","link":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/","title":{"rendered":"Google Search Console setup - 10 tips to get started"},"content":{"rendered":"<p>Wenn Sie eine Website haben, sind die kostenlosen <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Webmaster<\/span>-Tools von Google eine der wertvollesten Ressourcen, die man Nutzen kann. Deshalb sollte man sich unbedingt die Google Search Console einrichten.<\/p>\n<p>Ich denke mal, dass Sie Google Analytics bereits kennen und regelm&#xE4;&#xDF;ig nutzen. Doch falls nicht, sollten Sie die Google Search Console sp&#xE4;testen jetzt zur Liste Ihrer Google-Tools hinzuf&#xFC;gen und einrichten, denn damit k&#xF6;nnen Sie auf der Website Ihres Unternehmes definitiv noch mehr ausrichten.<\/p>\n<h2><strong>Google Search Console einrichten &#x2013; so geht&#x2019;s!<\/strong><\/h2>\n<p>Um mit dem Einrichten anzufangen rufen Sie erst einmal die Google Search Console auf. Um auf diese zugreifen zu k&#xF6;nnen, m&#xFC;ssen Sie sich mit Ihrem Google-Konto anmelden. Stellen Sie sicher, dass Sie das gleiche Konto verwenden, das Sie auch f&#xFC;r alle anderen von Ihnen verwendeten Google <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Webmaster<\/span>-Tools verwenden.<\/p>\n<p>Sobald Sie eingeloggt sind, suchen Sie nach der roten Schaltfl&#xE4;che mit der Aufschrift &#x201E;Property hinzuf&#xFC;gen&#x201C;. Geben Sie die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">URL<\/span> f&#xFC;r Ihre Website ein und klicken Sie auf &#x201E;Weiter&#x201C;.<\/p>\n<p>&#xA0;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2578\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-16.12.19-1024x502.png\" alt=\"Google Search Console einrichten\" width=\"576\" height=\"282\"\/><br>\nHier kann es sein, dass Google m&ouml;glicherweise &uuml;berpr&uuml;fen m&ouml;chte, ob Sie der Eigent&uuml;mer der Website sind. Es gibt ein paar verschiedene M&ouml;glichkeiten, das zu tun. Wenn Sie bereits Google Analytics verwenden, ist die einfachste Option, den Google Analytics Tracking Code als bevorzugte Verifizierungsmethode auszuw&auml;hlen. Solange sich Ihr Google Analytics-Tracking-Code im Abschnitt &lt;head&gt; Ihrer <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Homepage<\/span> befindet, wir das ohne Problem funktionieren.<\/p>\n<p>Wenn Sie sich auf der Startseite der Google Search Console befinden, finden Sie oben links den Link &#x201E;Probieren Sie die neue Search Console&#x201C;. Sie haben derzeit n&#xE4;mlich zwei Optionen f&#xFC;r die Verwendung des Tools: die alte, traditionelle, die mehr auf Funktionalit&#xE4;t ausgerichtet ist; und die neuere Version, die ein intuitiveres visuelles Design hat, aber wiederum weniger die Funktionalit&#xE4;t der &#xE4;lteren Version. Im Laufe der Zeit plant Google aber, alle Funktionen der Search Console in die neuere Version zu &#xFC;berf&#xFC;hren.<\/p>\n<p>In den folgenden Bildern ist die alte Version auf der linken Seite und die neue Version auf der rechten Seite:<\/p>\n<h2><strong><img decoding=\"async\" class=\"aligncenter wp-image-2764 size-large\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/01\/Bildschirmfoto-2019-01-06-um-00.55.11-1024x222.png\" alt=\"Google Search Console einrichten\" width=\"1024\" height=\"222\"\/><\/strong><\/h2>\n<p>&#xA0;<\/p>\n<h2><strong>10 M&#xF6;glichkeiten zur Verwendung der Google Search Console<\/strong><\/h2>\n<p>Mit der Google Search Console k&#xF6;nnen Sie direkt die Arbeit gehen und eine Reihe von Aufgaben erledigen. Hier sind einige der wichtigsten Punkte, die Sie angehen k&#xF6;nnen.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>1. Reichen Sie eine Sitemap ein<\/strong><\/h3>\n<p>Auch wenn die Google-<span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Webcrawler<\/span> automatisch Ihre Website crawlen werden, k&#xF6;nnen Sie ihnen durch die &#xDC;bermittlung einer <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Sitemap<\/span> an Google eine zus&#xE4;tzliche Hilfe beim &#xDC;bermitteln der ben&#xF6;tigten Informationen geben.<\/p>\n<p>Die meisten Websites generieren automatisch eine <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Sitemap<\/span> f&#xFC;r Sie. Sobald Sie diese haben, ist das &#xDC;bertragen jener in die Google Search Console sehr einfach.<\/p>\n<p>Wenn Sie sich auf der Hauptseite der alten Google Search Console Version befinden, sehen Sie auf der rechten Seite des Bildschirms den Abschnitt &#x201E;Sitemaps&#x201C;. Klicken Sie auf diesen.<\/p>\n<p>Suchen Sie dann nach der roten Schaltfl&#xE4;che &#x201E;Add\/Test Sitemaps&#x201C; in der oberen rechten Ecke des Bildschirms. Klicken Sie darauf und geben Sie die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">URL<\/span> f&#xFC;r die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Sitemap<\/span> Ihrer Website ein.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-2582\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-16.20.31-1024x453.png\" alt=\"Google Search Console einrichten\" width=\"699\" height=\"309\"\/><\/p>\n<p>Wenn Sie wiederum im <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Dashboard<\/span> der neuen Google Search Console befinden, klicken Sie auf &#x201E;Sitemaps&#x201C; im Men&#xFC; auf der linken Seite und geben Sie dann die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">URL<\/span> der <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Sitemap<\/span> ein.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2581\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-16.21.18-1024x456.png\" alt=\"Google Search Console einrichten\" width=\"647\" height=\"288\"\/><\/p>\n<p>&#xA0;<\/p>\n<h3><strong>2. Lernen Sie allgemeine Keywords, die Menschen verwenden, um Sie zu finden.<\/strong><\/h3>\n<p>Jeder, der Ihre Website &#xFC;ber die Suche findet, hat einen bestimmten Suchbegriff verwendet, um dorthin zu gelangen. Die Google Search Console zeigt Ihnen die h&#xE4;ufigsten Keywords, die Personen auf Ihre Website bringen.<\/p>\n<p>In der neuen Google Search Console finden Sie diese Informationen, indem Sie entweder im linken Men&#xFC; oder in der oberen Box im Haupt-<span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Dashboard<\/span> auf &#x201E;Leistung&#x201C; klicken.<\/p>\n<p>&#xA0;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2585\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-16.25.47-1024x327.png\" alt=\"Google Search Console einrichten\" width=\"666\" height=\"213\"\/><\/p>\n<p>&#xA0;<\/p>\n<p>In dieser Version zeigt Ihnen Google sowohl die Anzahl der Klicks, die jedes <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Keyword<\/span> einbringt, als auch die Anzahl der Impressionen die Ihre Website bei der Suche auf ein <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Keyword<\/span> hatte. Zus&#xE4;tzlich k&#xF6;nnen Sie sich auch andere Kategorien wie CTR oder Position anzeigen lassen, indem Sie auf das umgekehrte Dreieck &#xFC;ber der Liste klicken.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2584\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-16.26.50-1024x469.png\" alt=\"Google Search Console einrichten\" width=\"661\" height=\"303\"\/><\/p>\n<p>&#xA0;<\/p>\n<p>Diese Informationen zeigen Ihnen, ob Sie, basierend auf den Keywords, erfolgreich <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Traffic<\/span> auf Ihre Seite ziehen, welche Sie in Ihrer SEO-Stategie f&#xFC;r sich gew&#xE4;hlt haben. Au&#xDF;erdem zeigt es Ihnen nat&#xFC;rlich auch, welche Keywords hingegen leide nicht funktionieren und eben keinen <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Traffic<\/span> auf Ihre Website bringen.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>3. Identifizieren Sie Ihre beliebtesten Seiten.<\/strong><\/h3>\n<p>Jede Website wird Seiten haben, die in den Suchmaschinen besser abschneiden als andere. Mit der Google Search Console k&#xF6;nnen Sie feststellen, welche Ihrer Seiten die meisten Besucher auf Ihre Website bringt.<\/p>\n<p>Sie k&#xF6;nnen in beiden Versionen der Google Search Konsole Ihre beliebtesten Seiten im gleichen Abschnitt finden, in welchem Sie auch die Schl&#xFC;sselw&#xF6;rter gefunden haben, und das Filtern und Anzeigen nach den verschiedenen Metriken funktioniert dort genauso wie bei den Keywords.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2586\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-16.35.17-1024x543.png\" alt=\"Google Search Console einrichten\" width=\"685\" height=\"363\"\/>Du siehst hier eine Liste aller Seiten, die Leute gesehen und angeklickt haben, in absteigender Reihenfolge nach Klicks bzw. Beliebtheit. Die Standardansicht der alten Google Search Konsole Version zeigt Ihnen hierbei nur die beliebtesten Seiten in Bezug auf Klicks, in der neuen Version hingegen kommen auch noch die Impressionen dazu. Sie k&#xF6;nnen auch sehen, welche Seiten die besten Ergebnisse in Bezug auf Klickrate und Position erzielen.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>4. Sehen Sie, woher Ihre Besucher kommen.<\/strong><\/h3>\n<p>Das Einrichten der Google Search Console dient nat&#xFC;rlich auch der M&#xF6;glichkeit, zielgerichtet arbeiten zu k&#xF6;nnen. Wenn sich der Zielmarkt Ihres Unternehmens auf ein bestimmtes geografisches Gebiet begrenzt, dann ist es logischerweise am wichtigsten, Ihren <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Traffic<\/span> von dort zu erhalten. Die Google Search Console liefert Ihnen auch dazu Daten. Zum Beispiel, wo genau sich Ihre Besucher befinden, damit Sie sicherstellen k&#xF6;nnen, dass Sie die richtigen Personen erreichen.<\/p>\n<p>Das Ganze befindet sich im gleichen Abschnitt wie die Keywords und Seitendaten. Sie k&#xF6;nnen in beiden Versionen im Men&#xFC; L&#xE4;nder ausw&#xE4;hlen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2587\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-16.38.54-1024x611.png\" alt=\"Google Search Console einrichten\" width=\"628\" height=\"375\"\/><br>\nDort k&#xF6;nnen Sie die Anzahl der Klicks sehen, die Ihre Website auf jeweils welchem Land erh&#xE4;lt. Die h&#xF6;chsten Klickzahlen stehen hierbei ganz oben in der Liste. Wie bei den anderen Kategorien k&#xF6;nnen Sie auch hier w&#xE4;hlen, ob Sie die Ergebnisse basierend auf Impressionen, Klickrate oder Suchranking-Position anzeigen wollen.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>5. Erfahren Sie, welche Ger&#xE4;te sie verwenden.<\/strong><\/h3>\n<p>Inzwischen sollte jedes Unternehmen eine f&#xFC;r mobile Ger&#xE4;te taugliche Website haben. Aber selbst wenn Sie bereits Schritte unternommen haben, dass Ihre Website auf mobilen Ger&#xE4;ten gut aussieht, ist es immer noch gut zu wissen, wie genau sich die Verteilung der Nutzung Ihrer Website &#xFC;ber die jeweiligen Ger&#xE4;te gestaltet. Die Google Search Console kann Ihnen genau diese Daten liefern. Auch diese Daten kann man zu guter letzt im gleichen Abschnitt finden, wie die Daten, die wir zuvor behandelt haben.<\/p>\n<p>W&#xE4;hlen Sie in in der Men&#xFC;leiste &#x201E;Ger&#xE4;te&#x201C; aus, um die L&#xE4;nder-Verteilung der Klicks zu sehen.<\/p>\n<p>&#xA0;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2588\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-16.41.10-1024x358.png\" alt=\"Search Console\" width=\"580\" height=\"203\"\/><\/p>\n<p>&#xA0;<\/p>\n<p>Auch hier k&#xF6;nnen Sie die Liste wieder nach Klickrate oder Impressionen sortieren. Inzwischen kennen sie das ganze Spiel ja nun mittlerweile.<\/p>\n<p>Bitte beachten: Das hier ist der letzte Punkt auf unserer Liste, der in beiden Versionen des Produkts finden ist. Die nachfolgenden Punkte werden wir mit der alten Version der Google Search Console behandeln.<\/p>\n<p>&#xA0;<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>6. &#xDC;berpr&#xFC;fen Sie, ob Ihre Website auf dem Handy gut funktioniert.<\/strong><\/h3>\n<p>Es ist zwar eine gute Idee, mobile Tests auf Ihrer Website selbst durchzuf&#xFC;hren, aber Sie k&#xF6;nnen zur &#xDC;berpr&#xFC;fung Ihrer Website, auf Standards f&#xFC;r eine gute mobile Benutzerfreundlichkeit, auch die Google Search Console verwenden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2589\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-17.00.43-1024x480.png\" alt=\"\" width=\"648\" height=\"304\"\/>W&#xE4;hlen Sie im Abschnitt &#x201E;Search <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Traffic<\/span>&#x201C; auf der linken Seite des Men&#xFC;s &#x201E;Mobile Usability&#x201C;. Wenn alles auf Ihrer Website f&#xFC;r Google gut aussieht, was die Standards f&#xFC;r mobile Benutzerfreundlichkeit betrifft, sehen Sie die Angabe &#x201E;0 Fehler&#x201C;. Das sagt Ihnen, dass keine Fehler erkannt wurden.<\/p>\n<p>Wenn Google an Ihrer Website etwas findet, das auf dem Handy nicht gut funktioniert, wie z.B. die Verwendung von Flash oder einer kleinen Schriftgr&#xF6;&#xDF;e, erhalten Sie in diesem Bereich eine Nachricht, die Sie &#xFC;ber das Problem informiert, damit Sie an der Behebung arbeiten k&#xF6;nnen.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>7. Sehen Sie, welche Seiten auf Sie verweisen.<\/strong><\/h3>\n<p>F&#xFC;r alle, die sich auf SEO konzentrieren, sind dies alles wichtige Informationen. <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Backlinks<\/span> sind einer der gr&#xF6;&#xDF;ten <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Ranking<\/span>-Faktoren. Das hei&#xDF;t, dass jedes Mal, wenn eine andere vertrauensw&#xFC;rdige Website auf Sie verlinkt, steigt die Glaubw&#xFC;rdigkeit Ihrer Website wiederum in den Augen des Google-Algorithmus.<\/p>\n<p>W&#xE4;hlen Sie unter Search <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Traffic<\/span> im linken Men&#xFC; die Option Links zu Ihrer Website.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2590\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-17.06.16-1024x602.png\" alt=\"Suchkonsole\" width=\"648\" height=\"381\"\/><br>\nDort finden Sie eine Liste von Webseiten, die wiederum einen Link auf Ihre Website enthalten. Au&#xDF;erdem finden Sie dort eine Liste der Seiten auf Ihrer Website, die mit am meisten auf andere Websites verweisen. Unter dem Abschnitt &#x201E;Wie Ihre Daten verkn&#xFC;pft sind&#x201C; sehen Sie auch den Anker-Text, den andere Seiten am h&#xE4;ufigsten verwenden, wenn sie auf Ihre Seiten verlinken.<\/p>\n<p>Sie k&#xF6;nnen weitere Informationen zu jedem Backlink finden, indem Sie auf die Website klicken und dann auf den aufgelisteten Link klicken. Von dort aus k&#xF6;nnen Sie bestimmte Seiten mit dem Link aufrufen und selbst besuchen, um zu sehen, wie er verwendet wird.<\/p>\n<h3><strong>8. &#xDC;berpr&#xFC;fen Sie Ihre Website auf defekte Links.<\/strong><\/h3>\n<p>Kaputte Links bieten eine schlechte Erfahrung f&#xFC;r Ihre Benutzer und f&#xFC;hren die Leute von den funktionierenden Seiten weg, auf denen sie eigentlich landen sollten. Als ob das nicht schon schlimm genug w&#xE4;re, lassen dich diese Links auch f&#xFC;r Google schlecht aussehen und k&#xF6;nnen sich negativ auf deine Platzierungen auswirken.<\/p>\n<p>&#xA0;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2591\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-17.16.14-1024x631.png\" alt=\"404 Fehler Suchkonsole\" width=\"485\" height=\"299\"\/><\/p>\n<p>Im Crawl-Bereich der Google Search Console finden Sie Details zu allen Fehlern, die Google beim Crawlen Ihrer Website gefunden hat, einschlie&#xDF;lich aller URLs, die einen 404-Fehler ausgeben.<\/p>\n<p>Wenn Sie auf einen Eintrag klicken, finden Sie Informationen dar&#xFC;ber, was das Problem mit dem Link ist und wo sich der Link sowohl auf Ihrer Website als auch auf anderen befindet.<\/p>\n<p>Dies sind wertvolle Informationen, die Sie verwenden k&#xF6;nnen, um Ihr Website-Erlebnis zu verbessern und alle frustrierenden Fehler auszuschlie&#xDF;en, mit denen Ihre Besucher jetzt vielleicht noch zu tun haben.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>9. Identifizieren Sie Sicherheitsprobleme auf der Website.<\/strong><\/h3>\n<p>Von gro&#xDF;en Website-Hacks h&#xF6;rt man tagt&#xE4;glich in den Nachrichten. Selbst wenn Ihr Unternehmen vielleicht nicht gro&#xDF; genug ist, um in die Nachrichten zu kommen, wenn Sie gehackt werden; es kann es Ihnen trotzdem ernsthafte Probleme bereiten. Und das geht doppelt so schnell, wenn Sie eine <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">E-Commerce<\/span>-Site haben, die sensible Kundendaten wie Kreditkartendaten sammelt.<\/p>\n<p>Die Google Search Console bietet einen schnellen und einfachen &#xDC;berblick, wenn Ihre Website eine Sicherheitsl&#xFC;cke hat, auf die Sie achten sollten. Klicken Sie auf die Option &#x201E;Sicherheitsprobleme&#x201C; im linken Men&#xFC;. Wenn Sie keinen Grund zur Sorge haben brauchen, wird die Konsole Sie auch dar&#xFC;ber informieren.<\/p>\n<p>&#xA0;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2593\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-17.20.25-1024x203.png\" alt=\"\" width=\"756\" height=\"150\"\/><\/p>\n<p>Wenn Google ein Problem entdeckt, erfahren Sie hier die Details, die Sie ben&#xF6;tigen, um herauszufinden, wie Sie dieses Problem beheben k&#xF6;nnen.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>10. Vergewissern Sie sich, dass Ihr Schema-Markup oder strukturierte Daten funktionieren.<\/strong><\/h3>\n<p>Wenn Sie schlie&#xDF;lich Schema-Markup oder andere strukturierte Daten auf Ihrer Website verwenden, kann Google f&#xFC;r Sie &#xFC;berpr&#xFC;fen, ob alles richtig eingerichtet ist, um in die SERPs zu kommen.<\/p>\n<p>Unter &#x201E;Search Appearance&#x201C; finden Sie Kategorien f&#xFC;r Structured Data, Rich Cards und Data Highlighter, welches alles Methoden sind, mit denen Sie den Google-Crawlern mit weiteren Informationen helfen k&#xF6;nnen, Ihre Webseiten in den Suchergebnissen anzuzeigen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2594\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2018\/12\/Bildschirmfoto-2018-12-28-um-17.24.23-1024x445.png\" alt=\"\" width=\"704\" height=\"306\"\/><\/p>\n<p>Die Konsole gibt Auskunft dar&#xFC;ber, ob Sie alle Ihre Codierungen f&#xFC;r diese Kategorien eingerichtet haben oder nicht, oder ob Sie &#xC4;nderungen vornehmen m&#xFC;ssen.<\/p>\n<p>&#xA0;<\/p>\n<h4><strong>Fazit<\/strong><\/h4>\n<p>Die Google Search Console ist v&#xF6;llig kostenlos und, wie Sie sehen k&#xF6;nnen, gr&#xFC;ndlich mit n&#xFC;tzlichen Informationen f&#xFC;r jede gesch&#xE4;ftliche Website ausgestattet. Wenn Sie sich darum k&#xFC;mmern, wo und wie Sie in den Suchmaschinen auftauchen, ist dies Ihre beste Ressource, um in den verf&#xFC;gbaren Daten zu graben und damit einen Aktionsplan zu erstellen, f&#xFC;r ein noch besseres SEO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn Sie eine Website haben, sind die kostenlosen <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\"><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Webmaster<\/span><\/span>-Tools von Google eine der wertvollesten Ressourcen, die man Nutzen kann. Deshalb sollte man sich unbedingt die Google Search Console einrichten. Ich denke mal, dass Sie Google Analytics bereits kennen und regelm&#xE4;&#xDF;ig nutzen. Doch falls nicht, sollten Sie die Google Search Console sp&#xE4;testen jetzt zur Liste Ihrer [&#x2026;]<\/p>\n","protected":false},"author":3,"featured_media":15509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seo"],"acf":{"show_faq":true,"faq_q_1":"Was ist die Google Search Console?","faq_antwort_1":"Die Google Search Console ist eine kostenlose Plattform, die Webmastern hilft, die Sichtbarkeit ihrer Websites in den Suchergebnissen von Google zu verbessern. Es bietet viele praktische Tools und Berichte, mit denen Benutzer die Leistung ihrer Webseite auf verschiedene Arten verfolgen und optimieren k\u00f6nnen.","faq_q_2":"Wozu wird die Google Search Console verwendet?","faq_antwort_2":"Die Suchmaschine kann Ihnen helfen, Probleme auf Ihrer Website zu identifizieren, bevor Google diese entdeckt, und Ihnen helfen, sie zu beheben. Es kann auch helfen, die Leistung Ihrer Website zu verbessern, indem es Informationen \u00fcber die von Ihnen ausgef\u00fchrten Suchanfragen, die Klickrate und vieles mehr liefert.","faq_q_3":"Wie richte ich die Google Search Console ein?","faq_antwort_3":"Um die Google Search Console zu Ihrer Website hinzuzuf\u00fcgen, m\u00fcssen Sie zuerst ein Konto erstellen. Es ist ein sehr einfacher Prozess und schnell erledigt. Sie m\u00fcssen Ihre Website auf der Plattform anmelden und die erforderlichen Informationen bereitstellen. Nachdem Sie die notwendigen Schritte ausgef\u00fchrt haben, k\u00f6nnen Sie sofort mit der Verwaltung Ihrer Website beginnen.","faq_q_4":"Wie kann ich meine Website f\u00fcr die Google Search Console verifizieren?","faq_antwort_4":"Um Ihre Website zu verifizieren, m\u00fcssen Sie einen HTML-Tag auf Ihrer Website platzieren. Sie k\u00f6nnen den HTML-Tag auf der Suchmaschinen-Konsole erhalten und ihn zu Ihrer Website hinzuf\u00fcgen. Nachdem Sie den Tag eingef\u00fcgt haben, m\u00fcssen Sie die Site auf der Suchmaschinen-Konsole \u00fcberpr\u00fcfen, um sicherzustellen, dass die Verifizierung erfolgreich war.","faq_q_5":"Welche Tools bietet die Google Search Console?","faq_antwort_5":"Die Suchmaschinen-Konsole bietet viele leistungsstarke Tools, mit denen Benutzer die Leistung ihrer Webseite verfolgen und analysieren k\u00f6nnen. Dazu geh\u00f6ren das \u00dcberwachen der Sichtbarkeit der Website, das \u00dcberpr\u00fcfen von Fehlern auf der Website, die Analyse des Nutzerverhaltens, das Testen neuer Inhalte und mehr.","faq_q_6":"Kann ich mehrere Domains auf der Google Search Console hinzuf\u00fcgen?","faq_antwort_6":"Ja, Sie k\u00f6nnen mehrere Domains auf der Suchmaschinen-Konsole hinzuf\u00fcgen. Dazu m\u00fcssen Sie jedoch ein separates Konto f\u00fcr jede Domain erstellen. Sobald Sie die verschiedenen Konten erstellt haben, k\u00f6nnen Sie die Domains auf der Suchmaschinen-Konsole hinzuf\u00fcgen.","faq_q_7":"Wie kann ich das Suchverhalten meiner Nutzer auf meiner Website verfolgen?","faq_antwort_7":"Die Suchmaschinen-Konsole bietet ein Tool, das Ihnen hilft, das Suchverhalten Ihrer Nutzer auf Ihrer Website zu verfolgen. Mit diesem Tool k\u00f6nnen Sie den Suchverlauf Ihrer Nutzer verfolgen, um zu sehen, welche Suchbegriffe sie eingeben und welche Ergebnisse sie anzeigen lassen.","faq_q_8":"Kann ich meine Website in der Google-Suche optimieren?","faq_antwort_8":"Ja, die Suchmaschinen-Konsole bietet viele leistungsstarke Tools, mit denen Sie Ihre Website f\u00fcr die Google-Suche optimieren k\u00f6nnen. Mit den angebotenen Tools k\u00f6nnen Sie die richtigen Suchbegriffe ausw\u00e4hlen, Ihren Inhalt optimieren und mehr.","faq_q_9":"Welche Arten von Berichten bietet die Google Search Console?","faq_antwort_9":"Die Google Search Console bietet viele Berichte, mit denen Benutzer die Leistung ihrer Website verfolgen und analysieren k\u00f6nnen. Dazu geh\u00f6ren Berichte zu Suchanfragen, zur Klickrate, zu den Rankings der Website, zu Fehlern, zu Links und vieles mehr.","faq_q_10":" Was bedeutet die \"Impressions\" in den Berichten der Google Search Console?","faq_antwort_10":" \"Impressions\" bezieht sich auf die Anzahl der Mal, die Ihre Website in den Suchergebnissen von Google angezeigt wird. Es ist ein wichtiger Indikator, der Ihnen helfen kann, die Sichtbarkeit Ihrer Website in den Suchergebnissen von Google zu verstehen."},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Google Search Console einrichten | 10 Tipps f\u00fcr den Anfang - Wolf of SEO<\/title>\n<meta name=\"description\" content=\"Google Search Console einrichten - 10 hilfreiche Features des wertvollen Google Webmaster Tools f\u00fcr die kostenlose Analyse Ihrer Website-Daten. Lies mehr \u2714.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google Search Console einrichten - 10 Tipps f\u00fcr den Anfang\" \/>\n<meta property=\"og:description\" content=\"Google Search Console einrichten - 10 hilfreiche Features des wertvollen Google Webmaster Tools f\u00fcr die kostenlose Analyse Ihrer Website-Daten. Lies mehr \u2714.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/\" \/>\n<meta property=\"og:site_name\" content=\"WOLF OF SEO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wolf.of.seo.ns\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/n.sniprs\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-05T23:57:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-21T17:37:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/01\/google-search-console.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Niels Stuck\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wolf_of_seo\" \/>\n<meta name=\"twitter:site\" content=\"@wolf_of_seo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Niels Stuck\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/\"},\"author\":{\"name\":\"Niels Stuck\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/person\\\/013374d61ad2b66997fc16e2807fbbf7\"},\"headline\":\"Google Search Console einrichten &#8211; 10 Tipps f\u00fcr den Anfang\",\"datePublished\":\"2019-01-05T23:57:54+00:00\",\"dateModified\":\"2021-12-21T17:37:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/\"},\"wordCount\":1966,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/google-search-console.jpeg\",\"articleSection\":[\"SEO\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/\",\"name\":\"Google Search Console einrichten | 10 Tipps f\u00fcr den Anfang - Wolf of SEO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/google-search-console.jpeg\",\"datePublished\":\"2019-01-05T23:57:54+00:00\",\"dateModified\":\"2021-12-21T17:37:46+00:00\",\"description\":\"Google Search Console einrichten - 10 hilfreiche Features des wertvollen Google Webmaster Tools f\u00fcr die kostenlose Analyse Ihrer Website-Daten. Lies mehr \u2714.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/google-search-console.jpeg\",\"contentUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/google-search-console.jpeg\",\"caption\":\"google search console\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/blog\\\/google-search-console-features\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wolf-of-seo.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google Search Console einrichten &#8211; 10 Tipps f\u00fcr den Anfang\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#website\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/\",\"name\":\"WOLF OF SEO\",\"description\":\"Die E-Commerce SEO-Agentur\",\"publisher\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wolf-of-seo.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\",\"name\":\"WOLF OF SEO\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo_wos_beitragsbild3.jpg\",\"contentUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo_wos_beitragsbild3.jpg\",\"width\":1,\"height\":1,\"caption\":\"WOLF OF SEO\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wolf.of.seo.ns\",\"https:\\\/\\\/x.com\\\/wolf_of_seo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/person\\\/013374d61ad2b66997fc16e2807fbbf7\",\"name\":\"Niels Stuck\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9598d9b5cbe93cca9b08868beffeacf059426ba087d49d1eda3bbc9498e467aa?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9598d9b5cbe93cca9b08868beffeacf059426ba087d49d1eda3bbc9498e467aa?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9598d9b5cbe93cca9b08868beffeacf059426ba087d49d1eda3bbc9498e467aa?s=96&d=blank&r=g\",\"caption\":\"Niels Stuck\"},\"description\":\"Niels Stuck hat 10 Jahre SEO Erfahrung und ist Gr\u00fcnder der SEO Agentur \u201cWOLF OF SEO\u201d. Durch dem Aufbau von 20+ Affiliate-Seiten sammelte neben seinem Marketingstudium Praxiserfahrung. Abschlie\u00dfend schrieb er seine Bachelorarbeit \u00fcber den Einfluss von SEO auf Google Rankings, Traffic und Umsatzentwicklung in Form einer Case Study. Heute ist er spezialisiert auf E-Commerce-SEO und hilft mehr als 80 Unternehmen durch SEO einen nachhaltigen organischen Umsatzkanal aufzubauen. Niels ber\u00e4t Startups, etablierte Marken und Konzerne in der Suchmaschinenoptimierung Ihrer Onlineshops und setzt prim\u00e4r auf datenbasierte Contentstrategien und Linkbuilding. Sein Wissen \u00fcber SEO und Onlinemarketing teilt er in diesem Blog, als Speaker auf Konferenzen, in Podcasts und als Gastautor f\u00fcr OMT, Forbes, Starting Up und vielen weiteren Plattformen.\",\"sameAs\":[\"https:\\\/\\\/wolf-of-seo.de\\\/team-uebersicht\\\/niels-stuck\\\/\",\"https:\\\/\\\/www.facebook.com\\\/n.sniprs\\\/\",\"https:\\\/\\\/www.instagram.com\\\/nielsstuck.de\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/niels-stuck-082167113\\\/\",\"https:\\\/\\\/x.com\\\/wolf_of_seo\"],\"honorificSuffix\":\"B.Sc\",\"birthDate\":\"1995-10-22\",\"gender\":\"m\u00e4nnlich\",\"knowsAbout\":[\"SEO\",\"Onlinemarketing\",\"SEA\",\"Suchmachinenoptimierung\",\"Linkbuilding\",\"Contentmarketing\"],\"knowsLanguage\":[\"Deutsch\",\"Englisch\"],\"jobTitle\":\"CEO\",\"worksFor\":\"WOLF OF SEO FZ LLC\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Google Search Console setup | 10 tips to get started - Wolf of SEO","description":"Google Search Console setup - 10 helpful features of the valuable Google Webmaster Tool for free analysis of your website data. Read more \u2714.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/","og_locale":"en_US","og_type":"article","og_title":"Google Search Console einrichten - 10 Tipps f\u00fcr den Anfang","og_description":"Google Search Console einrichten - 10 hilfreiche Features des wertvollen Google Webmaster Tools f\u00fcr die kostenlose Analyse Ihrer Website-Daten. Lies mehr \u2714.","og_url":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/","og_site_name":"WOLF OF SEO","article_publisher":"https:\/\/www.facebook.com\/wolf.of.seo.ns","article_author":"https:\/\/www.facebook.com\/n.sniprs\/","article_published_time":"2019-01-05T23:57:54+00:00","article_modified_time":"2021-12-21T17:37:46+00:00","og_image":[{"url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/01\/google-search-console.jpeg","width":1,"height":1,"type":"image\/jpeg"}],"author":"Niels Stuck","twitter_card":"summary_large_image","twitter_creator":"@wolf_of_seo","twitter_site":"@wolf_of_seo","twitter_misc":{"Written by":"Niels Stuck","Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/#article","isPartOf":{"@id":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/"},"author":{"name":"Niels Stuck","@id":"https:\/\/wolf-of-seo.de\/#\/schema\/person\/013374d61ad2b66997fc16e2807fbbf7"},"headline":"Google Search Console einrichten &#8211; 10 Tipps f\u00fcr den Anfang","datePublished":"2019-01-05T23:57:54+00:00","dateModified":"2021-12-21T17:37:46+00:00","mainEntityOfPage":{"@id":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/"},"wordCount":1966,"commentCount":5,"publisher":{"@id":"https:\/\/wolf-of-seo.de\/#organization"},"image":{"@id":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/#primaryimage"},"thumbnailUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/01\/google-search-console.jpeg","articleSection":["SEO"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/","url":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/","name":"Google Search Console setup | 10 tips to get started - Wolf of SEO","isPartOf":{"@id":"https:\/\/wolf-of-seo.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/#primaryimage"},"image":{"@id":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/#primaryimage"},"thumbnailUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/01\/google-search-console.jpeg","datePublished":"2019-01-05T23:57:54+00:00","dateModified":"2021-12-21T17:37:46+00:00","description":"Google Search Console setup - 10 helpful features of the valuable Google Webmaster Tool for free analysis of your website data. Read more \u2714.","breadcrumb":{"@id":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/#primaryimage","url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/01\/google-search-console.jpeg","contentUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/01\/google-search-console.jpeg","caption":"google search console"},{"@type":"BreadcrumbList","@id":"https:\/\/wolf-of-seo.de\/en\/blog\/google-search-console-features\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wolf-of-seo.de\/"},{"@type":"ListItem","position":2,"name":"Google Search Console einrichten &#8211; 10 Tipps f\u00fcr den Anfang"}]},{"@type":"WebSite","@id":"https:\/\/wolf-of-seo.de\/#website","url":"https:\/\/wolf-of-seo.de\/","name":"WOLF OF SEO","description":"The e-commerce SEO agency","publisher":{"@id":"https:\/\/wolf-of-seo.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wolf-of-seo.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wolf-of-seo.de\/#organization","name":"WOLF OF SEO","url":"https:\/\/wolf-of-seo.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wolf-of-seo.de\/#\/schema\/logo\/image\/","url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2021\/11\/logo_wos_beitragsbild3.jpg","contentUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2021\/11\/logo_wos_beitragsbild3.jpg","width":1,"height":1,"caption":"WOLF OF SEO"},"image":{"@id":"https:\/\/wolf-of-seo.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wolf.of.seo.ns","https:\/\/x.com\/wolf_of_seo"]},{"@type":"Person","@id":"https:\/\/wolf-of-seo.de\/#\/schema\/person\/013374d61ad2b66997fc16e2807fbbf7","name":"Niels Stuck","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9598d9b5cbe93cca9b08868beffeacf059426ba087d49d1eda3bbc9498e467aa?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9598d9b5cbe93cca9b08868beffeacf059426ba087d49d1eda3bbc9498e467aa?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9598d9b5cbe93cca9b08868beffeacf059426ba087d49d1eda3bbc9498e467aa?s=96&d=blank&r=g","caption":"Niels Stuck"},"description":"Niels Stuck has 10 years of SEO experience and is the founder of the SEO agency \"WOLF OF SEO\". He gained practical experience by building 20+ affiliate sites alongside his marketing studies. Finally, he wrote his bachelor thesis about the influence of SEO on Google rankings, traffic and sales development in the form of a case study. Today, he specializes in e-commerce SEO and helps more than 80 companies build a sustainable organic revenue channel through SEO. Niels advises startups, established brands and corporations in search engine optimization of their online stores and primarily focuses on data-based content strategies and link building. He shares his knowledge about SEO and online marketing in this blog, as a speaker at conferences, in podcasts and as a guest author for OMT, Forbes, Starting Up and many more platforms.","sameAs":["https:\/\/wolf-of-seo.de\/team-uebersicht\/niels-stuck\/","https:\/\/www.facebook.com\/n.sniprs\/","https:\/\/www.instagram.com\/nielsstuck.de\/","https:\/\/www.linkedin.com\/in\/niels-stuck-082167113\/","https:\/\/x.com\/wolf_of_seo"],"honorificSuffix":"B.Sc","birthDate":"1995-10-22","gender":"m\u00e4nnlich","knowsAbout":["SEO","Onlinemarketing","SEA","Suchmachinenoptimierung","Linkbuilding","Contentmarketing"],"knowsLanguage":["Deutsch","Englisch"],"jobTitle":"CEO","worksFor":"WOLF OF SEO FZ LLC"}]}},"_links":{"self":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/posts\/2577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/comments?post=2577"}],"version-history":[{"count":0,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/posts\/2577\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/media\/15509"}],"wp:attachment":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/media?parent=2577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/categories?post=2577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/tags?post=2577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}