{"id":4047,"date":"2019-04-30T22:19:58","date_gmt":"2019-04-30T20:19:58","guid":{"rendered":"https:\/\/wolf-of-seo.de\/?post_type=glossary&#038;p=4047"},"modified":"2021-12-19T14:34:14","modified_gmt":"2021-12-19T13:34:14","slug":"online-reputation-management-standard","status":"publish","type":"glossary","link":"https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard","title":{"rendered":"Online Reputation Management (ORM)"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-5243\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/06\/Was-ist-38.png\" alt=\"Was ist Online Reputation Management\" width=\"750\" height=\"400\"\/><\/p>\n<h2><strong>Was ist Online Reputation Management (ORM)?<\/strong><\/h2>\n<p><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Online Reputation Management (ORM)<\/span> bedeutet, die Kontrolle &#xFC;ber Ihre Onlinerepr&#xE4;sentation zu &#xFC;bernehmen. Seine Techniken und Strategien stellen sicher, dass die Menschen die richtigen Materialien finden, wenn sie im Internet nach dir suchen.Wenn es gut umgesetzt wird, schafft das Online Reputation Management eine positive Repr&#xE4;sentation im Netz, wirkt irref&#xFC;hrenden Inhalten entgegen und erm&#xF6;glicht es Ihnen, sich von der besten Seite zu zeigen.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>Warum sollten Sie sich um Ihre Online-Reputation k&#xFC;mmern?<\/strong><\/h3>\n<p>Nun, du denkst vielleicht nicht, dass die Leute nach dir suchen, aber die Chancen stehen gut. H&#xE4;ufige Gr&#xFC;nde sind unter anderem:<\/p>\n<ul>\n<li>Arbeitgeber, die eine Vorbefragung durchf&#xFC;hren<\/li>\n<li>Vermieter bei der Suche nach potenziellen Mietern<\/li>\n<li>Kinder, die nach Details aus dem &#x201E;wirklichen Leben&#x201C; ihrer Eltern suchen.<\/li>\n<li>Neugierig gewordene bedeutende andere, Vergangenheit und Gegenwart<\/li>\n<li>Ehemalige Kollegen, die sich &#xFC;ber berufliche M&#xF6;glichkeiten austauschen m&#xF6;chten.<\/li>\n<li>Egal wie &#x201E;unter dem Radar&#x201C; oder &#x201E;Lowkey&#x201C; Ihr Lebensstil ist, es gibt eine gro&#xDF;e Menge an Informationen &#xFC;ber Sie online und die Leute sehen es.<\/li>\n<\/ul>\n<p>Wenn jemand etwas Negatives &#xFC;ber Sie online schreibt, kann es Sie langfristig ernsthaft sch&#xE4;digen. Dies gilt besonders wenn Sie es nicht wissen. Sie wissen vielleicht nie, warum Sie nicht die Wohnung bekommen haben, die Sie wollten, oder warum sich nach diesem ph&#xE4;nomenalen Interview nie ein Jobangebot ergeben hat.<\/p>\n<p>Es ist wichtig, im Auge zu behalten, was die Leute &#xFC;ber Sie online sagen, und dann Schritte zu unternehmen um Ungenauigkeiten zu korrigieren.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>Was sie &#xFC;ber Online Reputationsmanagement wissen sollten:<\/strong><\/h3>\n<ul>\n<li><strong>Alle <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchergebnisse<\/span> werden algorithmisch generiert.<\/strong> Ihre Online-Reputation wird durch komplexe Berechnungen bestimmt, die automatisch von Computern ausgef&#xFC;hrt werden. Schlie&#xDF;lich hat niemand Zeit, alle Informationen die es gibt manuell zu sortieren, also machen Suchmaschinen und Social Media Websites fundierte Vermutungen dar&#xFC;ber, was die Menschen interessant finden werden.<\/li>\n<li><strong>Popularit&#xE4;t &#xFC;berwiegt Fakten.<\/strong> Kein Algorithmus kann sagen, ob Informationen Sie genau widerspiegeln oder nicht, so dass die Popularit&#xE4;t zum wichtigsten Messstab wird. Deshalb dominieren peinliche Partyfotos, leichtfertige Klagen, die vor Jahren abgewiesen wurden, und andere Arten von irrelevanten, aber faszinierenden &#x201E;<span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Clickbait<\/span> Inhalte&#x201C; oft den Online-Ruf.<\/li>\n<li><strong>Was haben Sie aus Punkt 2 gelernt? Richtig, klicken Sie unerw&#xFC;nschte Beitr&#xE4;ge nicht st&#xE4;ndig an.<\/strong> Es kann verlockend sein, die negativen Seiten in Ihren Suchergebnissen immer wieder zu besuchen. Tun Sie das nicht. Dies teilt den Suchmaschinen mit, dass die Seite relevant ist und treibt sie in den Ergebnissen nach oben. Aus dem gleichen Grund solltest du nicht allen deinen Freunden sagen, dass sie die Seite besuchen sollen. Und unter keinen Umst&#xE4;nden sollten Sie darauf in Social Media oder von einer anderen Website verlinken.<\/li>\n<li><strong>Lassen Sie sich nicht mit Kritikern ein.<\/strong> Wenn jemand etwas Unangenehmes &#xFC;ber Sie schreibt, schreiben Sie nicht zur&#xFC;ck, posten keinen Kommentar und verweisen nicht auf das beleidigende Element in Online-Medien oder &#xE4;hnlichem. Alles, was dies tut, ist, mehr Aufmerksamkeit auf das Problem zu lenken, das du nicht sehen willst. Es besteht auch die Gefahr, dass wirklich b&#xF6;swillige Leute Ihre Antwort missbilligend aufnehmen und die Worte gegen Sie richten. Warum geben Sie ihnen zus&#xE4;tzliche Munition? Es ist besser, ihre Verspottungen mit Funkstille zu bek&#xE4;mpfen.<\/li>\n<li><strong>Erstellen Sie positiven Content, oder stellen Sie die Dinge klar.<\/strong> Sie k&#xF6;nnen nur die Materialien bewerben, die es tats&#xE4;chlich faktisch gibt. Das bedeutet, dass Sie eine solide Basis an positiven und wahren Inhalten ben&#xF6;tigen, um Ihre Online-Reputation zu verbessern. Sie k&#xF6;nnen dies selbst in gewissem Umfang in die Hand nehmen. So starten Sie zum Beispiel einen Blog, ver&#xF6;ffentlichen Sie YouTube-Videos, etc. &#x2013; aber Sie ben&#xF6;tigen m&#xF6;glicherweise ein Publikationsteam oder einen SEO Experten, um die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchergebnisse<\/span> zu beeinflussen.<\/li>\n<li><strong>Verwenden Sie Social Media smart<\/strong>. Nicht auf Twitter? Registrieren Sie sich mit Ihrem vollst&#xE4;ndigen Namen als Nickname. Sind Sie bei LinkedIn aktiv? Stellen Sie sicher, dass Ihr Lebenslauf auf dem neuesten Stand ist. Social Media-Websites ranken oft gut in den Suchergebnissen und Sie kontrollieren die Inhalte, die sie anzeigen, so dass sie einen gro&#xDF;en Unterschied f&#xFC;r Ihre Online-Reputation machen k&#xF6;nnen.<\/li>\n<li><strong>Sch&#xFC;tzen Sie Ihre Privatsph&#xE4;re.<\/strong> Behalten Sie die personenbezogenen Daten &#xFC;ber Ihre online ver&#xF6;ffentlichten Daten im Auge. Deaktivieren Sie Dienste, die Ihre personenbezogenen Daten verkaufen, und entfernen Sie Ihre Daten von Personensuchseiten. Dies macht es unwahrscheinlicher, dass sensible personenbezogene Daten verwendet werden k&#xF6;nnen, um Ihren Online-Ruf zu missbrauchen.<\/li>\n<li><strong>Nehmen Sie an, alles dauert ewig.<\/strong> Wenn etwas online ver&#xF6;ffentlicht wurde, ist es m&#xF6;glicherweise Teil Ihrer permanenten Online-Reputation. Die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchergebnisse<\/span> sind nicht chronologisch geordnet, so dass alte Nachrichten, veraltete Informationen und Geschichten von vor Jahren weiterhin ein <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Ranking<\/span> einnehmen k&#xF6;nnen, wenn sie von Suchmaschinen als relevant angesehen werden. Dies kann f&#xFC;r oder gegen dich arbeiten.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Was ist <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\"><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Online Reputation Management (ORM)<\/span><\/span>? <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\"><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Online Reputation Management (ORM)<\/span><\/span> bedeutet, die Kontrolle &#xFC;ber Ihre Onlinerepr&#xE4;sentation zu &#xFC;bernehmen. Seine Techniken und Strategien stellen sicher, dass die Menschen die richtigen Materialien finden, wenn sie im Internet nach dir suchen.Wenn es gut umgesetzt wird, schafft das Online Reputation Management eine positive Repr&#xE4;sentation im Netz, wirkt irref&#xFC;hrenden Inhalten [&#x2026;]<\/p>\n","protected":false},"author":3,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4047","glossary","type-glossary","status-publish","hentry"],"acf":{"show_faq":true,"faq_q_1":"Was ist ein ORM?","faq_antwort_1":"ORM steht f\u00fcr Object-Relational Mapping und ist ein Programmierwerkzeug, das es Programmierern erm\u00f6glicht, Daten aus einer relationalen Datenbank in einem objektorientierten Programmiersprache darzustellen und zu manipulieren.","faq_q_2":"Warum sollte ich meine Datenbank \u00fcber ein ORM abbilden?","faq_antwort_2":"ORM ist ein wichtiges Werkzeug, um relationale Datenbanken in einem objektorientierten Programmiersprache darzustellen und zu manipulieren. ORM kann viele Probleme l\u00f6sen, die mit der direkten Verwendung einer relationalen Datenbank entstehen k\u00f6nnen, wie z.B. eine schlechte Leistung, ein hoher Kode-Redundanz und schlecht lesbarer Code.","faq_q_3":"Wie wirkt sich das Verwenden eines ORM auf die Performance aus?","faq_antwort_3":"ORM kann dazu beitragen, die Performance Ihrer Anwendung zu verbessern. Es kann Ihnen helfen, den Datenbank-Code besser lesbar und wiederverwendbar zu machen und dadurch besser lesbare und effizientere Code-Snippets zu erzeugen. Au\u00dferdem k\u00f6nnen ORM-Frameworks den Programmierern helfen, optimierte SQL-Abfragen zu erstellen, die wiederum die Performance Ihrer Anwendung verbessern k\u00f6nnen.","faq_q_4":"Welches ORM-Framework sollte ich verwenden?","faq_antwort_4":"Welches Framework f\u00fcr Sie am besten geeignet ist, h\u00e4ngt von Ihren Anforderungen an die Leistung ab. Einige der beliebtesten ORM-Frameworks sind Entity Framework, Hibernate und Doctrine. Es ist wichtig, ein Framework auszuw\u00e4hlen, das Ihren Anforderungen und denen Ihrer Anwendung entspricht.","faq_q_5":"Wie werden ORM-Frameworks verwendet?","faq_antwort_5":"ORM-Frameworks k\u00f6nnen verwendet werden, um den Code Ihrer Anwendungen besser lesbar und wiederverwendbar zu machen. Sie k\u00f6nnen auch dazu verwendet werden, Datenbankabfragen zu erstellen und zu verwalten. Au\u00dferdem k\u00f6nnen sie helfen, Code-Redundanz zu vermeiden, indem sie eine einheitliche Schnittstelle f\u00fcr die Verwaltung von Datenbanken bereitstellen. ","faq_q_6":"K\u00f6nnen ORM-Frameworks auch mit NoSQL-Datenbanken verwendet werden?","faq_antwort_6":"Ja, einige ORM-Frameworks unterst\u00fctzen auch die Verwendung mit NoSQL-Datenbanken. Zum Beispiel k\u00f6nnen Sie Hibernate verwenden, um Abfragen in MongoDB, Cassandra und vielen anderen NoSQL-Datenbanken durchzuf\u00fchren.","faq_q_7":"Kann ich mein eigenes ORM-Framework erstellen?","faq_antwort_7":"Ja, es ist m\u00f6glich, ein eigenes ORM-Framework zu erstellen. Allerdings ist es sehr schwierig und erfordert viel Zeit und M\u00fche. Es wird empfohlen, ein vorhandenes ORM-Framework zu verwenden, da dies eine einfachere und schnellere M\u00f6glichkeit ist, Ihre Anforderungen zu erf\u00fcllen.","faq_q_8":"Wem kann ich bei Fragen zu ORM helfen?","faq_antwort_8":"Es gibt eine Reihe von verschiedenen Quellen, an die Sie sich wenden k\u00f6nnen, wenn Sie Fragen zur Verwendung von ORM haben. Sie k\u00f6nnen z.B. den ORM-Framework-Entwicklern Fragen stellen, die die entsprechende ORM-Dokumentation durchlesen oder verschiedene Online-Foren oder Q&A-Websites besuchen.","faq_q_9":"Wie kann ich sicherstellen, dass mein ORM-Setup sicher ist?","faq_antwort_9":"Um sicherzustellen, dass Ihr ORM-Setup sicher ist, m\u00fcssen Sie zun\u00e4chst sicherstellen, dass Sie das richtige ORM-Framework f\u00fcr Ihre Anforderungen ausgew\u00e4hlt haben. Es ist auch wichtig, dass Sie alle notwendigen Sicherheitsvorkehrungen treffen, wie z.B. das Erstellen eines sicheren Passworts, und dass Sie alle Anwendungen, die Sie mit Ihrem ORM-Framework erstellen, regelm\u00e4\u00dfig auf Sicherheitsl\u00fccken \u00fcberpr\u00fcfen.","faq_q_10":"Welche Probleme k\u00f6nnen auftreten, wenn man ein ORM-Framework verwendet?","faq_antwort_10":"Einige der h\u00e4ufigsten Probleme, die bei der Verwendung von ORM-Frameworks auftreten k\u00f6nnen, sind schlechte Leistung, schlecht lesbarer Code und schlechte Wiederverwendbarkeit. Diese Probleme sind jedoch leicht zu vermeiden, indem man sich an bestimmte Regeln f\u00fcr die Verwendung von ORM-Frameworks h\u00e4lt."},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Was ist Online Reputation Management (ORM)? | WOLF OF SEO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Online Reputation Management (ORM)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard\/\" \/>\n<meta property=\"og:site_name\" content=\"WOLF OF SEO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wolf.of.seo.ns\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-19T13:34:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/06\/Was-ist-38.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wolf_of_seo\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/what-is\\\/online-reputation-management-standard\\\/\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/what-is\\\/online-reputation-management-standard\\\/\",\"name\":\"Was ist Online Reputation Management (ORM)? | WOLF OF SEO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/what-is\\\/online-reputation-management-standard\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/what-is\\\/online-reputation-management-standard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Was-ist-38.png\",\"datePublished\":\"2019-04-30T20:19:58+00:00\",\"dateModified\":\"2021-12-19T13:34:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/what-is\\\/online-reputation-management-standard\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/what-is\\\/online-reputation-management-standard\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/what-is\\\/online-reputation-management-standard\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Was-ist-38.png\",\"contentUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Was-ist-38.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/en\\\/what-is\\\/online-reputation-management-standard\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wolf-of-seo.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online Reputation Management (ORM)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#website\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/\",\"name\":\"WOLF OF SEO\",\"description\":\"Die E-Commerce SEO-Agentur\",\"publisher\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wolf-of-seo.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\",\"name\":\"WOLF OF SEO\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo_wos_beitragsbild3.jpg\",\"contentUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo_wos_beitragsbild3.jpg\",\"width\":1,\"height\":1,\"caption\":\"WOLF OF SEO\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wolf.of.seo.ns\",\"https:\\\/\\\/x.com\\\/wolf_of_seo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"What is Online Reputation Management (ORM)? | WOLF OF SEO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard\/","og_locale":"en_US","og_type":"article","og_title":"Online Reputation Management (ORM)","og_url":"https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard\/","og_site_name":"WOLF OF SEO","article_publisher":"https:\/\/www.facebook.com\/wolf.of.seo.ns","article_modified_time":"2021-12-19T13:34:14+00:00","og_image":[{"url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/06\/Was-ist-38.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@wolf_of_seo","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard\/","url":"https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard\/","name":"What is Online Reputation Management (ORM)? | WOLF OF SEO","isPartOf":{"@id":"https:\/\/wolf-of-seo.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard\/#primaryimage"},"image":{"@id":"https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard\/#primaryimage"},"thumbnailUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/06\/Was-ist-38.png","datePublished":"2019-04-30T20:19:58+00:00","dateModified":"2021-12-19T13:34:14+00:00","breadcrumb":{"@id":"https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard\/#primaryimage","url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/06\/Was-ist-38.png","contentUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/06\/Was-ist-38.png"},{"@type":"BreadcrumbList","@id":"https:\/\/wolf-of-seo.de\/en\/what-is\/online-reputation-management-standard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wolf-of-seo.de\/"},{"@type":"ListItem","position":2,"name":"Online Reputation Management (ORM)"}]},{"@type":"WebSite","@id":"https:\/\/wolf-of-seo.de\/#website","url":"https:\/\/wolf-of-seo.de\/","name":"WOLF OF SEO","description":"The e-commerce SEO agency","publisher":{"@id":"https:\/\/wolf-of-seo.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wolf-of-seo.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wolf-of-seo.de\/#organization","name":"WOLF OF SEO","url":"https:\/\/wolf-of-seo.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wolf-of-seo.de\/#\/schema\/logo\/image\/","url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2021\/11\/logo_wos_beitragsbild3.jpg","contentUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2021\/11\/logo_wos_beitragsbild3.jpg","width":1,"height":1,"caption":"WOLF OF SEO"},"image":{"@id":"https:\/\/wolf-of-seo.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wolf.of.seo.ns","https:\/\/x.com\/wolf_of_seo"]}]}},"_links":{"self":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/glossary\/4047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/glossary\/4047\/revisions"}],"wp:attachment":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/media?parent=4047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}