{"id":3949,"date":"2019-04-29T15:48:56","date_gmt":"2019-04-29T13:48:56","guid":{"rendered":"https:\/\/wolf-of-seo.de\/?post_type=glossary&#038;p=3949"},"modified":"2021-12-19T14:34:28","modified_gmt":"2021-12-19T13:34:28","slug":"compression","status":"publish","type":"glossary","link":"https:\/\/wolf-of-seo.de\/en\/what-is\/compression","title":{"rendered":"Compression"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-5185\" src=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/06\/Was-ist-18-1.png\" alt=\"Was ist Komprimierung\" width=\"750\" height=\"400\"\/><\/p>\n<h2><strong>Was ist Komprimierung<\/strong><\/h2>\n<p>Wenn es um die Generierung einer Seite oder die Ausf&#xFC;hrung eines Skripts geht, sind Webbrowser nicht an der Lesbarkeit von Code interessiert. Die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Komprimierung<\/span> entfernt eine Code-Datei mit allen Daten, die nicht ben&#xF6;tigt werden, damit die Datei ausgef&#xFC;hrt werden kann. Im Gegensatz zu herk&#xF6;mmlichen Komprimierungstechniken m&#xFC;ssen verkleinerte Dateien nicht dekomprimiert werden, bevor sie gelesen, ge&#xE4;ndert oder ausgef&#xFC;hrt werden k&#xF6;nnen.<\/p>\n<p>Die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Komprimierung<\/span> wird durchgef&#xFC;hrt, nachdem der Code f&#xFC;r eine Webanwendung geschrieben wurde, aber bevor die Anwendung bereitgestellt wird. Wenn ein Benutzer eine Webseite anfordert, wird die verkleinerte Version anstelle der Vollversion gesendet, was zu schnelleren Reaktionszeiten und niedrigeren Bandbreitenkosten f&#xFC;hrt. Die Minifizierung wird auf Websites verwendet, die von kleinen pers&#xF6;nlichen Blogs bis hin zu millionenschweren Benutzerdiensten reichen.<\/p>\n<h3><\/h3>\n<h3><strong>Wie funktioniert Komprimierung?<\/strong><\/h3>\n<p>Die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Komprimierung<\/span> funktioniert, indem sie die textbasierten Teile einer Website analysiert und neu schreibt, um ihre Gesamtdateigr&#xF6;&#xDF;e zu reduzieren. Die Minifizierung erstreckt sich auf Skripte, <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Stylesheets<\/span> und andere Komponenten, die der Webbrowser zur Darstellung der Website verwendet.<\/p>\n<p>Eine <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Komprimierung<\/span> wird auf dem Webserver durchgef&#xFC;hrt, bevor eine Antwort gesendet wird. Nach der Anpassung verwendet der Webserver die verkleinerten Assets anstelle der urspr&#xFC;nglichen Assets, um die Verteilung an die Benutzer zu beschleunigen.<\/p>\n<p>Hier ist eine Schritt-f&#xFC;r-Schritt-Anleitung, wie die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Komprimierung<\/span> funktioniert:<\/p>\n<ol>\n<li><strong>Ein Webentwickler erstellt eine <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">JavaScript<\/span>- oder CSS-Datei,<\/strong> die in einer Webanwendung verwendet werden soll. Diese Dateien sind f&#xFC;r den Entwickler komfortabel formatiert, d.h. sie verwenden Leerzeichen, Kommentare, lange Variablennamen und andere Praktiken zur besseren Lesbarkeit.<\/li>\n<li><strong>Der Entwickler wendet eine Komprimierungstechnik<\/strong> <strong>(siehe unten) an<\/strong>, um die Datei in eine Datei zu konvertieren, die optimiert, aber schwerer zu lesen ist. Zu den g&#xE4;ngigen Minifizierungstechniken geh&#xF6;ren das Entfernen von Leerzeichen, das Verk&#xFC;rzen von Variablennamen und das Ersetzen von ausf&#xFC;hrlichen Funktionen durch k&#xFC;rzere, pr&#xE4;gnantere Funktionen.<\/li>\n<li><strong>Der Webserver verwendet die verkleinerte Datei,<\/strong> wenn er auf Webanfragen reagiert, was zu einer geringeren Bandbreitenauslastung f&#xFC;hrt, ohne die Funktionalit&#xE4;t zu beeintr&#xE4;chtigen.<\/li>\n<\/ol>\n<p>Der Vorteil der <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Komprimierung<\/span> besteht darin, dass sie nur durchgef&#xFC;hrt werden muss, wenn sich die Quelldatei &#xE4;ndert. In Kombination mit anderen Komprimierungstechniken kann die Miniaturisierung die Bandbreitenauslastung sowohl f&#xFC;r das Unternehmen als auch f&#xFC;r den Benutzer erheblich reduzieren.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>Komprimierungstechniken und -werkzeuge<\/strong><\/h3>\n<p>Eines der umfangreicheren Minifizierungswerkzeuge ist <strong>Minify<\/strong>. Das sogenannte Minify &#xFC;bernimmt die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Komprimierung<\/span>, das <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Caching<\/span> und die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Komprimierung<\/span> von CSS-, HTML- und <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">JavaScript<\/span>-Dateien. Zudem bietet Minify auch die Integration mit g&#xE4;ngigen Webanwendungen und Frameworks wie WordPress und dem Zend Framework.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>Was ist HTML-Komprimierung?<\/strong><\/h3>\n<p>Google bietet die Erweiterung <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">PageSpeed<\/span> Insights Chrome an, die Leistungssteigerungen f&#xFC;r jede Website empfiehlt. Das Tool &#x201E;<span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">PageSpeed<\/span> Insights&#x201C; stellt eine &#x201E;Minify HTML&#x201C;-Regel zur Verf&#xFC;gung, die eine verkleinerte Version der ge&#xF6;ffneten Website erzeugt.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>Was ist CSS-Komprimierung?<\/strong><\/h3>\n<p>Da CSS seltener h&#xE4;ufig ge&#xE4;ndert wird, bieten mehrere Online-Tools eine sofortige CSS-<span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Komprimierung<\/span>. Zum Beispiel der CSS Minifier ist eine schnelle und einfache M&#xF6;glichkeit, CSS zu komprimieren, w&#xE4;hrend Refresh-SF mehrere Tools verwendet, um CSS, HTML und <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">JavaScript<\/span> zu komprimieren.<\/p>\n<p>&#xA0;<\/p>\n<h3><strong>Was ist JavaScript Komprimierung?<\/strong><\/h3>\n<p>Googles <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">JavaScript<\/span>-Optimierungstool &#x2013; der Closure <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Compiler<\/span> &#x2013; erstellt eine effizientere Kopie jeder <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">JavaScript<\/span>-Datei. Wenn ein Entwickler eine &#xC4;nderung an einer <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">JavaScript<\/span>-Datei vornimmt, verwendet er oder sie den Closure <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Compiler<\/span>, um den Code zu komprimieren. Die neue Datei wird auf den Webserver &#xFC;bertragen, wo sie mit dem Webbrowser eines Benutzers abgerufen werden kann.<\/p>\n<p>&#xA0;<\/p>\n<h2><strong>Vorteile der Komprimierung<\/strong><\/h2>\n<ul>\n<li><strong>Benutzer laden Inhalte schneller<\/strong>, da weniger unn&#xF6;tige Daten heruntergeladen werden m&#xFC;ssen. Die Benutzer erleben einen identischen Service ohne den zus&#xE4;tzlichen Aufwand.<\/li>\n<li><strong>Unternehmen haben geringere Bandbreitenkosten<\/strong>, da weniger Daten &#xFC;ber das Netzwerk &#xFC;bertragen werden. Der zus&#xE4;tzliche Inhalt, der nur Entwicklern wichtig ist, wird nicht mehr an Benutzer gesendet.<\/li>\n<li><strong>Unternehmen haben auch einen geringeren Ressourcenverbrauch<\/strong>, da f&#xFC;r jede Anfrage weniger Daten verarbeitet werden m&#xFC;ssen. Der verkleinerte Inhalt &#x2013; der nur einmal generiert werden muss &#x2013; kann f&#xFC;r eine unbegrenzte Anzahl von Anfragen verwendet werden.<\/li>\n<\/ul>\n<p>&#xA0;<\/p>\n<h3><strong>Fazit zur Datenkomprimierung<\/strong><\/h3>\n<p>Die Minifizierung ist ein schneller und einfacher Weg, um den Ressourcenverbrauch einer Webanwendung zu reduzieren. Selbst mit Standard-Komprimierungstechniken kann die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Komprimierung<\/span> die Zeit, die f&#xFC;r das Rendern einer Seite ben&#xF6;tigt wird, um &#xFC;ber 60% verbessern. Die Anpassung Ihrer Website kann zu gro&#xDF;en Leistungssteigerungen f&#xFC;hren, ohne die Benutzerfreundlichkeit zu beeintr&#xE4;chtigen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was ist <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\"><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Komprimierung<\/span><\/span> Wenn es um die Generierung einer Seite oder die Ausf&#xFC;hrung eines Skripts geht, sind Webbrowser nicht an der Lesbarkeit von Code interessiert. Die <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\"><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Komprimierung<\/span><\/span> entfernt eine Code-Datei mit allen Daten, die nicht ben&#xF6;tigt werden, damit die Datei ausgef&#xFC;hrt werden kann. Im Gegensatz zu herk&#xF6;mmlichen Komprimierungstechniken m&#xFC;ssen verkleinerte Dateien nicht dekomprimiert werden, bevor [&#x2026;]<\/p>\n","protected":false},"author":3,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3949","glossary","type-glossary","status-publish","hentry"],"acf":{"show_faq":true,"faq_q_1":"Was bedeutet komprimieren?","faq_antwort_1":"Komprimieren ist ein Prozess, bei dem Daten komprimiert werden, um den Speicherplatz zu reduzieren, den sie ben\u00f6tigen. Der Komprimierungsprozess erm\u00f6glicht es, Daten schneller zu \u00fcbertragen und gleichzeitig Speicherplatz zu sparen.","faq_q_2":"Wie komprimiere ich Daten?","faq_antwort_2":"Es gibt verschiedene Verfahren zur Komprimierung von Daten, einschlie\u00dflich der Verwendung von Verlustkompressionsverfahren, verlustfreien Kompressionsverfahren und verschiedener Arten von Archivierungssoftware.","faq_q_3":"Welche Vorteile hat das Komprimieren von Daten?","faq_antwort_3":"Wenn Daten komprimiert werden, k\u00f6nnen sie schneller gesendet und empfangen werden und es wird weniger Speicherplatz ben\u00f6tigt. Au\u00dferdem kann die Kompression den Bandbreitenverbrauch verringern, was die Daten\u00fcbertragungsgeschwindigkeit erh\u00f6ht.","faq_q_4":"Wie komprimiere ich eine Datei?","faq_antwort_4":"Der Komprimierungsprozess ist abh\u00e4ngig von der verwendeten Software. Die meisten Programme erm\u00f6glichen es dem Benutzer, mehrere Dateien gleichzeitig zu komprimieren.","faq_q_5":"Welche Arten von Dateien k\u00f6nnen komprimiert werden?","faq_antwort_5":"Viele Dateiformate k\u00f6nnen komprimiert werden, einschlie\u00dflich Textdateien, Bilddateien, Video- und Audiodateien und sogar komprimierte Archivdateien.","faq_q_6":"Wie gro\u00df ist die Komprimierungsrate?","faq_antwort_6":"Die Komprimierungsrate h\u00e4ngt von der Art der Datei ab. In der Regel ist die Komprimierungsrate f\u00fcr Textdateien h\u00f6her als f\u00fcr Bild-, Video- und Audiodateien.","faq_q_7":"Kann man die Komprimierungsrate erh\u00f6hen?","faq_antwort_7":"In der Regel kann die Komprimierungsrate erh\u00f6ht werden, indem ein besseres Kompressionsverfahren verwendet wird.","faq_q_8":"Wie sicher sind komprimierte Dateien?","faq_antwort_8":"Komprimierte Dateien sind sicher, solange sie mit einem geeigneten Sicherheitsprotokoll verschl\u00fcsselt werden.","faq_q_9":"K\u00f6nnen komprimierte Dateien wiederhergestellt werden?","faq_antwort_9":"Ja, die meisten komprimierten Dateien k\u00f6nnen mithilfe der entsprechenden Software wiederhergestellt werden.","faq_q_10":" Kann man komprimierte Dateien bearbeiten?","faq_antwort_10":" Ja, komprimierte Dateien k\u00f6nnen mithilfe der entsprechenden Software bearbeitet werden. Dies kann manchmal eine Herausforderung sein, da die Dateien in komprimierter Form vorliegen."},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Was bedeutet Komprimierung und Mifnify? - SEO Glossar | WOLF OF SEO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wolf-of-seo.de\/en\/what-is\/compression\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Komprimierung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wolf-of-seo.de\/en\/what-is\/compression\/\" \/>\n<meta property=\"og:site_name\" content=\"WOLF OF SEO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wolf.of.seo.ns\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-19T13:34:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/06\/Was-ist-18-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wolf_of_seo\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/komprimierung\\\/\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/komprimierung\\\/\",\"name\":\"Was bedeutet Komprimierung und Mifnify? - SEO Glossar | WOLF OF SEO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/komprimierung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/komprimierung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Was-ist-18-1.png\",\"datePublished\":\"2019-04-29T13:48:56+00:00\",\"dateModified\":\"2021-12-19T13:34:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/komprimierung\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/komprimierung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/komprimierung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Was-ist-18-1.png\",\"contentUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Was-ist-18-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/komprimierung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wolf-of-seo.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Komprimierung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#website\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/\",\"name\":\"WOLF OF SEO\",\"description\":\"Die E-Commerce SEO-Agentur\",\"publisher\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wolf-of-seo.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\",\"name\":\"WOLF OF SEO\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo_wos_beitragsbild3.jpg\",\"contentUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo_wos_beitragsbild3.jpg\",\"width\":1,\"height\":1,\"caption\":\"WOLF OF SEO\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wolf.of.seo.ns\",\"https:\\\/\\\/x.com\\\/wolf_of_seo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"What does compression and Mifnify mean? - SEO Glossary | WOLF OF SEO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wolf-of-seo.de\/en\/what-is\/compression\/","og_locale":"en_US","og_type":"article","og_title":"Komprimierung","og_url":"https:\/\/wolf-of-seo.de\/en\/what-is\/compression\/","og_site_name":"WOLF OF SEO","article_publisher":"https:\/\/www.facebook.com\/wolf.of.seo.ns","article_modified_time":"2021-12-19T13:34:28+00:00","og_image":[{"url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/06\/Was-ist-18-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@wolf_of_seo","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wolf-of-seo.de\/was-ist\/komprimierung\/","url":"https:\/\/wolf-of-seo.de\/was-ist\/komprimierung\/","name":"What does compression and Mifnify mean? - SEO Glossary | WOLF OF SEO","isPartOf":{"@id":"https:\/\/wolf-of-seo.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wolf-of-seo.de\/was-ist\/komprimierung\/#primaryimage"},"image":{"@id":"https:\/\/wolf-of-seo.de\/was-ist\/komprimierung\/#primaryimage"},"thumbnailUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/06\/Was-ist-18-1.png","datePublished":"2019-04-29T13:48:56+00:00","dateModified":"2021-12-19T13:34:28+00:00","breadcrumb":{"@id":"https:\/\/wolf-of-seo.de\/was-ist\/komprimierung\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wolf-of-seo.de\/was-ist\/komprimierung\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wolf-of-seo.de\/was-ist\/komprimierung\/#primaryimage","url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/06\/Was-ist-18-1.png","contentUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2019\/06\/Was-ist-18-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/wolf-of-seo.de\/was-ist\/komprimierung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wolf-of-seo.de\/"},{"@type":"ListItem","position":2,"name":"Komprimierung"}]},{"@type":"WebSite","@id":"https:\/\/wolf-of-seo.de\/#website","url":"https:\/\/wolf-of-seo.de\/","name":"WOLF OF SEO","description":"The e-commerce SEO agency","publisher":{"@id":"https:\/\/wolf-of-seo.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wolf-of-seo.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wolf-of-seo.de\/#organization","name":"WOLF OF SEO","url":"https:\/\/wolf-of-seo.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wolf-of-seo.de\/#\/schema\/logo\/image\/","url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2021\/11\/logo_wos_beitragsbild3.jpg","contentUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2021\/11\/logo_wos_beitragsbild3.jpg","width":1,"height":1,"caption":"WOLF OF SEO"},"image":{"@id":"https:\/\/wolf-of-seo.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wolf.of.seo.ns","https:\/\/x.com\/wolf_of_seo"]}]}},"_links":{"self":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/glossary\/3949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/glossary\/3949\/revisions"}],"wp:attachment":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/media?parent=3949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}