{"id":15886,"date":"2021-12-28T20:45:15","date_gmt":"2021-12-28T19:45:15","guid":{"rendered":"https:\/\/wolf-of-seo.de\/?post_type=glossary&#038;p=15886"},"modified":"2023-01-14T16:20:49","modified_gmt":"2023-01-14T15:20:49","slug":"google-search-commands","status":"publish","type":"glossary","link":"https:\/\/wolf-of-seo.de\/en\/what-is\/google-search-commands","title":{"rendered":"Google Search Commands"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-31570\\&#x201C; src=\" https: alt=\"Was ist Google Suche Befehle\" width=\"750\" height=\"400\" srcset=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Google-Suche-Befehle.jpg 750w, https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Google-Suche-Befehle.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"\/><\/p>\n<p>F&#xE4;llt es dir schwer, im Internet genau das zu finden, was du brauchst? Warum versuchst du es nicht mit den Google-Suchoperatoren?<\/p>\n<p>Um dir zu helfen, das zu finden, was du suchst, enth&#xE4;lt Google spezielle Zeichen und Befehle, die Google-Suchoperatoren genannt werden. Sie helfen dir, etwas Bestimmtes zu finden, bestimmte Begriffe von Suchmaschinen zu ignorieren (breite Keywords), zwischen bestimmten Datumsbereichen zu suchen und vieles mehr.<\/p>\n<p>In diesem Beitrag stellen wir dir die g&#xE4;ngigsten Google-Suchoperatoren vor, mit denen du deine <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchergebnisse<\/span> verbessern kannst, und erl&#xE4;utern sie anhand konkreter Beispiele.<\/p>\n<p>Los geht&#x2019;s!<\/p>\n<h1 id=\"h-zehn-nutzliche-google-suchoperatoren\">Zehn n&#xFC;tzliche Google-Suchoperatoren<\/h1>\n<h2 id=\"h-1-exakte-ubereinstimmung-mit-suchen\">1. Exakte &#xDC;bereinstimmung mit &#x201C;&#x201D; suchen<\/h2>\n<p>Operator: &#x201C;[Begriff]&#x201D;<\/p>\n<p>Beispiel: &#x201C;Domain-Namen-Generatoren&#x201D;<\/p>\n<p>Beispiel erkl&#xE4;rt: gibt nur <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchergebnisse<\/span> zur&#xFC;ck, die den exakten Begriff &#x201C;domain name generators&#x201D; enthalten.<\/p>\n<p>Der erste in unserer Liste der g&#xE4;ngigen Google-Suchoperatoren ist &#x201C;&#x201D;. Es ist ein einfacher Suchoperator, der Google dazu zwingt, die exakte Entsprechung des Suchbegriffs zu finden, den du in Anf&#xFC;hrungszeichen setzt. Das ist besonders hilfreich, wenn du Details &#xFC;ber einen bestimmten Blog oder eine bestimmte Website finden m&#xF6;chtest.<\/p>\n<p>Wenn du diesen Suchoperator verwendest, werden alle Webseiten mit diesem Suchbegriff in der <a href=\"https:\/\/wolf-of-seo.de\/blog\/optimierung-der-suchergebnisse-serps-optimierung\/\" data-internallinksmanager029f6b8e52c=\"74\" title=\"Click Through Rate\">SERP<\/a> aufgelistet.<\/p>\n<h2 id=\"h-2-suche-den-inhalt-einer-bestimmten-website-mit-site\">2. Suche den Inhalt einer bestimmten Website mit site:<\/h2>\n<p>Operator: site:[<span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">url<\/span><\/span>] [term]<\/p>\n<p>Beispiel: site:themeisle.com wordpress hosting<\/p>\n<p>Beispiel erkl&#xE4;rt: sucht nach allen Seiten, die mit WordPress Hosting auf der Themeisle Website &#xFC;bereinstimmen.<\/p>\n<p>Site: ist ein toller Suchoperator, den du verwenden kannst, um etwas auf einer bestimmten Website zu finden (achte darauf, den Doppelpunkt bei der Suche beizubehalten). Du kannst ihn verwenden, wenn du einen Beitrag auf einem bestimmten Blog sehen m&#xF6;chtest oder wenn auf der Website keine Suchleiste vorhanden ist.<\/p>\n<p>Viele <a href=\"https:\/\/wolf-of-seo.de\" data-internallinksmanager029f6b8e52c=\"19\" title=\"SEO Agentur\">SEO-Experte<\/a>n nutzen ihn auch, um die Kontaktseite der Website zu finden, wenn sie schlechte Links entfernen. Dieser Befehl zeigt nicht nur die Seiten der Websites an, sondern auch die Sub-Domain.<\/p>\n<h2 id=\"h-3-fuge-ein-fill-in-the-blank-mit-hinzu\">3. F&#xFC;ge ein &#x201C;fill in the blank&#x201D; mit * hinzu<\/h2>\n<p>Operator: [Begriff1] * [Begriff2]<\/p>\n<p>Beispiel: WordPress * Entwickler<\/p>\n<p>Beispiel erkl&#xE4;rt: schlie&#xDF;t Ergebnisse ein, die zus&#xE4;tzlichen Inhalt zwischen WordPress und Entwickler haben (genauere Beispiele unten).<\/p>\n<p>Dies ist unserer Meinung nach einer der coolsten Google-Suchoperatoren auf unserer Liste. Mit einem Sternchen kannst du zwei verschiedene Suchbegriffe miteinander verbinden und <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchergebnisse<\/span> finden, die beide enthalten. Sieh es als eine Art &#x201C;L&#xFC;ckenf&#xFC;ller&#x201D; f&#xFC;r alles, was zwischen deinen beiden Suchbegriffen steht.<\/p>\n<p>Zum Beispiel w&#xFC;rde wordpress * entwickler Phrasen wie folgende ergeben:<\/p>\n<p>WordPress-<span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Plugin<\/span><\/span>-Entwickler<\/p>\n<p>WordPress Theme-Entwickler<\/p>\n<p>WordPress PHP-Entwickler<\/p>\n<p>Etc.<\/p>\n<h2 id=\"h-4-erzwinge-die-ubereinstimmung-eines-einzelnen-wortes-oder-satzes-mit\">4. Erzwinge die &#xDC;bereinstimmung eines einzelnen Wortes oder Satzes mit +<\/h2>\n<h2 id=\"h-operator-begriff1-begriff2\">Operator: [Begriff1] +[Begriff2]<\/h2>\n<p>Beispiel: Autos +tesla<\/p>\n<p>Beispiel erkl&#xE4;rt: zeigt alle Ergebnisse f&#xFC;r Autos, die auch Tesla enthalten<\/p>\n<p>Die Google-Suchoperatoren geben dir auch die M&#xF6;glichkeit, einen bestimmten Begriff in deine <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchergebnisse<\/span> aufzunehmen. Du kannst + Suchbegriff verwenden, um eine genaue &#xDC;bereinstimmung mit einem einzelnen Wort zu erzwingen. Wenn du zum Beispiel nach Autos suchst, die von Tesla hergestellt wurden, kannst du die beiden W&#xF6;rter mit dem + Zeichen dazwischen verwenden.<\/p>\n<p>Um noch genauer zu sein, kannst du die Zeichenfolge auch in Anf&#xFC;hrungszeichen setzen.<\/p>\n<h2 id=\"h-5-worter-oder-phrasen-mit-ausschliessen\">5. W&#xF6;rter oder Phrasen mit &#x2013; ausschlie&#xDF;en<\/h2>\n<p>Operator: [Begriff1] -[Begriff2]<\/p>\n<p>Beispiel: Autos -tesla<\/p>\n<p>Beispiel erkl&#xE4;rt: zeigt alle Ergebnisse f&#xFC;r Autos an, au&#xDF;er denen, die Tesla enthalten.<\/p>\n<p>Dieser Google-Operator ist genau das Gegenteil von dem oben genannten. Das Minuszeichen wird vor dem Suchbegriff verwendet, um ein bestimmtes Stichwort aus den Suchergebnissen zu entfernen. Es ist besonders hilfreich, wenn du nach etwas suchst, das mehr als eine Bedeutung hat und du die andere Bedeutung ausschlie&#xDF;en m&#xF6;chtest.<\/p>\n<h2 id=\"h-6-gib-die-gecachte-version-einer-seite-mit-cache-zuruck\">6. Gib die gecachte Version einer Seite mit Cache zur&#xFC;ck:<\/h2>\n<p>Operator: cache:[<span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">url<\/span><\/span>]<\/p>\n<p>Beispiel: cache:themeisle.com<\/p>\n<p>Beispiel erkl&#xE4;rt: gibt die zuletzt gecachte Version der Themeisle-<span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Homepage<\/span><\/span> zur&#xFC;ck.<\/p>\n<p>Der Cache ist ein erweiterter Suchoperator. Wenn du diesen Operator verwendest, erh&#xE4;ltst du die zuletzt gecachte Version der Webseite, die bei Google verf&#xFC;gbar ist.<\/p>\n<p>Beachte jedoch, dass er dir nicht die neueste Version einer Seite anzeigt, sondern nur die zuletzt gecrawlte Version, sofern die Seite indiziert ist. Um die Funktion zu nutzen, gib einfach das Wort &#x201C;cache&#x201D; gefolgt von der <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">URL<\/span><\/span> ein, nach der du suchst. Das kann besonders hilfreich sein, wenn eine Seite nicht erreichbar ist und du trotzdem einen Beitrag lesen m&#xF6;chtest.<\/p>\n<h2 id=\"h-7-suche-zwischen-daten-mit-daterange\">7. Suche zwischen Daten mit daterange:<\/h2>\n<p>Operator: [term1] daterange:XXXXX-XXXXX<\/p>\n<p>Beispiel: Themeisle daterange:19001-19365<\/p>\n<p>Beispiel erkl&#xE4;rt: enth&#xE4;lt alle Ergebnisse, die auf ThemeIsle passen und im Jahr 2019 ver&#xF6;ffentlicht wurden (19001-19365 im julianischen Datumsformat).<\/p>\n<p>Angenommen, du willst die neuesten Informationen zu einem Suchbegriff sehen. Wie w&#xFC;rdest du das machen? Du kannst einfach den Operator daterange verwenden.<\/p>\n<p>Dieser erweiterte Suchoperator hilft dir, Ergebnisse innerhalb eines bestimmten Datumsbereichs zu finden. Er verwendet das julianische Datumsformat, du musst also das Jahr gefolgt von der Anzahl der Tage seit Jahresbeginn eingeben.<\/p>\n<p>Tipp: Wenn du mit dem julianischen Datum nicht zurechtkommst, kannst du diesen Konverter verwenden, um die richtigen Zahlen zu finden.<\/p>\n<h2 id=\"h-8-suche-in-den-urls-der-ergebnisse-mit-inurl\">8. Suche in den URLs der Ergebnisse mit inurl:<\/h2>\n<p>Operator: <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">inurl<\/span><\/span>:[term1] [term2]<\/p>\n<p>Beispiel: <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">inurl<\/span><\/span>:guest-post WordPress<\/p>\n<p>Beispiel erkl&#xE4;rt: schlie&#xDF;t alle Ergebnisse f&#xFC;r WordPress ein, die den <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">URL<\/span><\/span>-Slug guest-post irgendwo in ihrer <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">URL<\/span><\/span> enthalten.<\/p>\n<p>Dieser Google-Suchoperator hilft dir, ein bestimmtes Schl&#xFC;sselwort innerhalb einer <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">URL<\/span><\/span> zu finden. Das hei&#xDF;t, wenn du nach einem Beitrag in einer <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">URL<\/span><\/span> suchst, z.B. zum Thema eCommerce, kannst du das Wort eCommerce nach dem <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">inurl<\/span><\/span>: Operator verwenden.<\/p>\n<p>Alternativ kannst du auch einen breiten Begriff vor dem Operator verwenden und dann das <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Keyword<\/span><\/span> hinzuf&#xFC;gen, das in der <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">URL<\/span><\/span> vorkommen soll.<\/p>\n<h2 id=\"h-9-suche-nach-bestimmten-dateitypen-mit-filetype\">9. Suche nach bestimmten Dateitypen mit filetype:<\/h2>\n<p>Operator: filetype:[file_extension] [term]<\/p>\n<p>Beispiel: Facebook filetype:pdf<\/p>\n<p>Beispiel erkl&#xE4;rt: schlie&#xDF;t nur PDF-Dokumente ein, die den Begriff Facebook enthalten.<\/p>\n<p>Dies ist einer der n&#xFC;tzlichsten erweiterten Google-Suchoperatoren, der dir hilft, die Zielseite mit einem bestimmten Format zu finden.<\/p>\n<p>Er schr&#xE4;nkt deine <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchergebnisse<\/span> auf ein bestimmtes Dateiformat wie PDF, TXT und dergleichen ein. Wenn du also Dokumente zu dem Thema, das du recherchierst, finden m&#xF6;chtest, kannst du das mit dem Suchoperator &#x201C;Dateityp&#x201D; tun. Ich pers&#xF6;nlich nutze ihn, um PDF-Berichte f&#xFC;r die Erstellung von Statistiken f&#xFC;r Websites wie HubSpot und Facebook zu finden.<\/p>\n<h2 id=\"h-10-suche-zwischen-den-jahren-mit\">10. Suche zwischen den Jahren mit ..<\/h2>\n<p>Operator: [Begriff] [Jahr]&#x2026;[Jahr2]<\/p>\n<p>Beispiel: WordCamp Ank&#xFC;ndigung 2018..2020<\/p>\n<p>Beispiel erkl&#xE4;rt: enth&#xE4;lt alle Ergebnisse zwischen 2018 und 2020, die mit WordCamp-Ank&#xFC;ndigung &#xFC;bereinstimmen.<\/p>\n<p>Dies ist der letzte Suchoperator auf unserer Liste. Er ist dem daterange-Operator sehr &#xE4;hnlich, nur dass er nicht dem julianischen Datumsformat folgt.<\/p>\n<p>Mit .. kannst du zwischen zwei Jahresbereichen suchen. Allerdings kannst du damit nicht nach bestimmten Tagen suchen, wie es bei daterange m&#xF6;glich ist.<\/p>\n<h1 id=\"h-letzte-worte\">Letzte Worte<\/h1>\n<p>Die Google-Suchoperatoren werden in einfache und erweiterte Operatoren unterteilt. Wir haben nur ein paar von ihnen aufgelistet, und es gibt noch viele andere Suchoperatoren.<\/p>\n<p>Wenn du die oben genannten Operatoren jedoch richtig einsetzt, reicht das aus, um genau das zu finden, was du brauchst. Du kannst sie sogar miteinander kombinieren, um noch pr&#xE4;zisere Ergebnisse zu erhalten.<\/p>\n<p>Wenn du den Dreh erst einmal raus hast, kannst du die Suchoperatoren nutzen, um die SEO deiner Website zu verbessern, M&#xF6;glichkeiten f&#xFC;r Gastbeitr&#xE4;ge zu finden und vieles mehr.<\/p>\n<p>Ich hoffe, dieser Beitrag hat dir geholfen, etwas Neues &#xFC;ber die Google-<span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchmaschine<\/span><\/span> zu lernen. Hast du schon einen der oben genannten Operatoren verwendet? Wie haben sie sich f&#xFC;r dich bew&#xE4;hrt?&#xA0;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":31570,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-15886","glossary","type-glossary","status-publish","has-post-thumbnail","hentry"],"acf":{"show_faq":true,"faq_q_1":"Was sind Google Suchbefehle?","faq_antwort_1":"Google Suchbefehle sind spezifische W\u00f6rter oder Zeichen, die man zu einer Google-Suche hinzuf\u00fcgen kann, um die Ergebnisse zu spezifizieren oder zu verfeinern. Zum Beispiel k\u00f6nnen Sie ein Suchbefehl wie \"Site: example.com\" verwenden, um nur Ergebnisse von einer bestimmten Website anzuzeigen.","faq_q_2":"Wie verwende ich Google Suchbefehle?","faq_antwort_2":"Google Suchbefehle k\u00f6nnen verwendet werden, um Ihre Ergebnisse zu spezifizieren. Sie werden hinzugef\u00fcgt, indem Sie sie vor oder nach Ihrer Suchanfrage eingeben. Zum Beispiel k\u00f6nnen Sie \"site: example.com\"verwenden, um die Ergebnisse auf eine bestimmte Website zu beschr\u00e4nken.","faq_q_3":"Welche Arten von Google Suchbefehlen gibt es?","faq_antwort_3":"Es gibt viele verschiedene Arten von Google Suchbefehlen. Einige Beispiele sind: Site: um Ergebnisse auf einer bestimmten Website zu beschr\u00e4nken; inurl: um Ergebnisse auf der Grundlage der URL zu beschr\u00e4nken; OR: um Ergebnisse auf der Grundlage mehrerer Begriffe zu beschr\u00e4nken; und filetype: um Ergebnisse auf der Grundlage eines bestimmten Dateityps zu beschr\u00e4nken.","faq_q_4":"Kann ich mehr als einen Google Suchbefehl pro Suche verwenden?","faq_antwort_4":"Ja, Sie k\u00f6nnen mehrere Google Suchbefehle in einer Suche verwenden. Sie k\u00f6nnen jedoch nicht mehr als 10 Suchbefehle pro Suche verwenden.","faq_q_5":"Wie kann ich meine Ergebnisse besser spezifizieren?","faq_antwort_5":"Sie k\u00f6nnen Ihre Ergebnisse mithilfe von Google Suchbefehlen spezifischer machen. Zum Beispiel k\u00f6nnen Sie ein Suchbefehl wie \"Site: example.com\" verwenden, um nur Ergebnisse von einer bestimmten Website anzuzeigen. Sie k\u00f6nnen auch mehrere Suchbefehle kombinieren, um die Ergebnisse auf einer breiteren Grundlage zu spezifizieren.","faq_q_6":"Kann ich meine Suchergebnisse auf einer bestimmten Website begrenzen?","faq_antwort_6":"Ja, Sie k\u00f6nnen Ihre Suchergebnisse auf einer bestimmten Website begrenzen, indem Sie den Suchbefehl \"site: example.com\" verwenden. Dies beschr\u00e4nkt Ihre Ergebnisse auf Ergebnisse, die nur auf der angegebenen Website vorhanden sind.","faq_q_7":"Kann ich meine Suchergebnisse auf einen bestimmten Dateityp beschr\u00e4nken?","faq_antwort_7":"Ja, Sie k\u00f6nnen Ihre Suchergebnisse auf einen bestimmten Dateityp beschr\u00e4nken, indem Sie den Suchbefehl \"filetype: [dateityp]\" verwenden. Dies beschr\u00e4nkt Ihre Ergebnisse auf Ergebnisse, die den angegebenen Dateityp enthalten.","faq_q_8":"Kann ich mehrere Suchbegriffe in einer Suche verwenden?","faq_antwort_8":"Ja, Sie k\u00f6nnen mehrere Suchbegriffe in einer Suche verwenden, indem Sie den Suchbefehl \"OR\" verwenden. Dies erm\u00f6glicht es Ihnen, Ergebnisse auf der Grundlage mehrerer Begriffe anzuzeigen.","faq_q_9":"Kann ich meine Suchergebnisse auf der Grundlage der URL beschr\u00e4nken?","faq_antwort_9":"Ja, Sie k\u00f6nnen Ihre Ergebnisse auf der Grundlage der URL beschr\u00e4nken, indem Sie den Suchbefehl \"inurl: [URL]\" verwenden. Dies beschr\u00e4nkt Ihre Ergebnisse auf Ergebnisse, die die angegebene URL enthalten.","faq_q_10":" Werden Google Suchbefehle f\u00fcr mobile Suchanfragen unterst\u00fctzt?","faq_antwort_10":" Ja, Google Suchbefehle werden f\u00fcr mobile Suchanfragen unterst\u00fctzt. Sie k\u00f6nnen den gleichen Suchbefehl auf Ihrem mobilen Ger\u00e4t wie auf Ihrem Desktop-Computer verwenden."},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Was sind Google Suche Befehle? | WOLF OF SEO<\/title>\n<meta name=\"description\" content=\"Hier findest Du eine Reihe hilfreicher Tipps, um effektiver mit der Suchmaschine Google umzugehen. So findest Du genau das, was Du suchst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wolf-of-seo.de\/en\/what-is\/google-search-commands\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google Suche Befehle\" \/>\n<meta property=\"og:description\" content=\"Hier findest Du eine Reihe hilfreicher Tipps, um effektiver mit der Suchmaschine Google umzugehen. So findest Du genau das, was Du suchst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wolf-of-seo.de\/en\/what-is\/google-search-commands\/\" \/>\n<meta property=\"og:site_name\" content=\"WOLF OF SEO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wolf.of.seo.ns\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-14T15:20:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Google-Suche-Befehle.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wolf_of_seo\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/google-suche-befehle\\\/\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/google-suche-befehle\\\/\",\"name\":\"Was sind Google Suche Befehle? | WOLF OF SEO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/google-suche-befehle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/google-suche-befehle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Google-Suche-Befehle.jpg\",\"datePublished\":\"2021-12-28T19:45:15+00:00\",\"dateModified\":\"2023-01-14T15:20:49+00:00\",\"description\":\"Hier findest Du eine Reihe hilfreicher Tipps, um effektiver mit der Suchmaschine Google umzugehen. So findest Du genau das, was Du suchst.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/google-suche-befehle\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/google-suche-befehle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/google-suche-befehle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Google-Suche-Befehle.jpg\",\"contentUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Google-Suche-Befehle.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/google-suche-befehle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wolf-of-seo.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google Suche Befehle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#website\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/\",\"name\":\"WOLF OF SEO\",\"description\":\"Die E-Commerce SEO-Agentur\",\"publisher\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wolf-of-seo.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\",\"name\":\"WOLF OF SEO\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo_wos_beitragsbild3.jpg\",\"contentUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo_wos_beitragsbild3.jpg\",\"width\":1,\"height\":1,\"caption\":\"WOLF OF SEO\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wolf.of.seo.ns\",\"https:\\\/\\\/x.com\\\/wolf_of_seo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"What are Google search commands? | WOLF OF SEO","description":"Here you will find a number of helpful tips to deal more effectively with the search engine Google. So you will find exactly what you are looking for.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wolf-of-seo.de\/en\/what-is\/google-search-commands\/","og_locale":"en_US","og_type":"article","og_title":"Google Suche Befehle","og_description":"Hier findest Du eine Reihe hilfreicher Tipps, um effektiver mit der Suchmaschine Google umzugehen. So findest Du genau das, was Du suchst.","og_url":"https:\/\/wolf-of-seo.de\/en\/what-is\/google-search-commands\/","og_site_name":"WOLF OF SEO","article_publisher":"https:\/\/www.facebook.com\/wolf.of.seo.ns","article_modified_time":"2023-01-14T15:20:49+00:00","og_image":[{"url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Google-Suche-Befehle.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@wolf_of_seo","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wolf-of-seo.de\/was-ist\/google-suche-befehle\/","url":"https:\/\/wolf-of-seo.de\/was-ist\/google-suche-befehle\/","name":"What are Google search commands? | WOLF OF SEO","isPartOf":{"@id":"https:\/\/wolf-of-seo.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wolf-of-seo.de\/was-ist\/google-suche-befehle\/#primaryimage"},"image":{"@id":"https:\/\/wolf-of-seo.de\/was-ist\/google-suche-befehle\/#primaryimage"},"thumbnailUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Google-Suche-Befehle.jpg","datePublished":"2021-12-28T19:45:15+00:00","dateModified":"2023-01-14T15:20:49+00:00","description":"Here you will find a number of helpful tips to deal more effectively with the search engine Google. So you will find exactly what you are looking for.","breadcrumb":{"@id":"https:\/\/wolf-of-seo.de\/was-ist\/google-suche-befehle\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wolf-of-seo.de\/was-ist\/google-suche-befehle\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wolf-of-seo.de\/was-ist\/google-suche-befehle\/#primaryimage","url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Google-Suche-Befehle.jpg","contentUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Google-Suche-Befehle.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/wolf-of-seo.de\/was-ist\/google-suche-befehle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wolf-of-seo.de\/"},{"@type":"ListItem","position":2,"name":"Google Suche Befehle"}]},{"@type":"WebSite","@id":"https:\/\/wolf-of-seo.de\/#website","url":"https:\/\/wolf-of-seo.de\/","name":"WOLF OF SEO","description":"The e-commerce SEO agency","publisher":{"@id":"https:\/\/wolf-of-seo.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wolf-of-seo.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wolf-of-seo.de\/#organization","name":"WOLF OF SEO","url":"https:\/\/wolf-of-seo.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wolf-of-seo.de\/#\/schema\/logo\/image\/","url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2021\/11\/logo_wos_beitragsbild3.jpg","contentUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2021\/11\/logo_wos_beitragsbild3.jpg","width":1,"height":1,"caption":"WOLF OF SEO"},"image":{"@id":"https:\/\/wolf-of-seo.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wolf.of.seo.ns","https:\/\/x.com\/wolf_of_seo"]}]}},"_links":{"self":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/glossary\/15886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/glossary\/15886\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/media\/31570"}],"wp:attachment":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/media?parent=15886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}