{"id":15672,"date":"2021-12-22T18:44:07","date_gmt":"2021-12-22T17:44:07","guid":{"rendered":"https:\/\/wolf-of-seo.de\/?post_type=glossary&#038;p=15672"},"modified":"2023-01-14T16:24:38","modified_gmt":"2023-01-14T15:24:38","slug":"low-hanging-fruits","status":"publish","type":"glossary","link":"https:\/\/wolf-of-seo.de\/en\/what-is\/low-hanging-fruits","title":{"rendered":"Low Hanging Fruits"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-31581\\&#x201C; src=\" https: alt=\"Was ist Low Hanging Fruits\" width=\"750\" height=\"400\" srcset=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Low-Hanging-Fruits.jpg 750w, https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Low-Hanging-Fruits.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"\/><\/p>\n<p>In der <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Online-Marketing<\/span><\/span> Welt beschreibt man mit dem Ausdruck &#x201C;<meta charset=\"utf-8\"><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Low Hanging Fruits<\/span><\/span>&#x201D;  Ziele, Projekte oder Aufgaben die leicht und ohne viel Aufwand erledigt werden k&#xF6;nnen, bevor man sich anspruchsvolleren Aufgaben zuwendet. Der Ausdruck gilt als Metapher f&#xFC;r die weiter unten h&#xE4;ngenden Fr&#xFC;chte eines Baumes, die leichter zu greifen sind. <\/p>\n<p>Um die besten Resultate zu erzielen, ist es wichtig zu verstehen, welche <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Low Hanging Fruits<\/span><\/span> deinem Unternehmen die besten Chancen bieten.<\/p>\n\n<h2>Wende dich an ehemalige Kunden<\/h2>\n<p>Ehemalige Kunden sind ein gefundenes Fressen, denn sie sind mit deinen Produkten und Dienst<a href=\"https:\/\/wolf-of-seo.de\/leistungen\/\" data-internallinksmanager029f6b8e52c=\"80\" title=\"SEO Leistungen\">leistungen<\/a> vertraut und es kann dadurch leichter sein, sie zu einem erneuten Kauf zu bewegen. Dies ist besonders wirkungsvoll, wenn sie in der Vergangenheit gute Erfahrungen gemacht haben. Wenn du ein Online-Gesch&#xE4;ft hast, kannst du diese Kunden beispielsweise per Newsletter ansprechen. <\/p>\n<p>Schicke ihnen eine E-Mail mit einem speziellen Rabatt oder schlage ihnen Artikel vor, die mit ihren letzten Suchen und Eink&#xE4;ufen zusammenh&#xE4;ngen. <\/p>\n\n<h2>Low Hanging Fruits &#x2013; wie findet man sie?<\/h2>\n<p>Wir k&#xF6;nnen das Thema in zwei Bereiche unterteilen: zum einen die Konzentration auf wettbewerbsschwache Suchbegriffe (z.B. Longtail-Begriffe) und zum anderen auf Rankings zwischen Position 10 und 20. Warum das? Wenn du bereits auf der zweiten Seite der Google <a href=\"https:\/\/wolf-of-seo.de\/blog\/optimierung-der-suchergebnisse-serps-optimierung\/\" data-internallinksmanager029f6b8e52c=\"74\" title=\"Click Through Rate\">SERP<\/a>s rangierst, ist klar, dass deine Seite relevant ist &#x2013; schon kleine Verbesserungen k&#xF6;nnen dir helfen, die erste Seite zu erreichen &#x2013; und dort ist der wahre <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Traffic<\/span><\/span> zu holen!<\/p>\n\n<p>Du solltest die <a href=\"https:\/\/wolf-of-seo.de\/blog\/10-funktionen-google-search-console\/\" data-internallinksmanager029f6b8e52c=\"75\" title=\"Google Search Console\">Google Search Console<\/a> oder <a href=\"https:\/\/wolf-of-seo.de\/blog\/unsere-top-10-seo-tools\/\" data-internallinksmanager029f6b8e52c=\"68\" title=\"SEO Tools\">SEO Tools<\/a> nutzen, um deine Rankingpositionen zwischen 10 und 20 zu analysieren. Die Google Search Console liefert dir dabei immer die validesten Daten und die besten Einblicke.<\/p>\n<p>Gehe in der Google Search Console in den Bericht &#x201C;Leistung&#x201D; und setze Filter f&#xFC;r die Keywords der letzten 12 Monate zwischen den Positionen 10 und 20. Filtere in absteigender Reihenfolge.<\/p>\n<p>Sieh dir die Impressionen dieser Keywords an &#x2013; diese geben wertvolle R&#xFC;ckschl&#xFC;sse auf das <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchvolumen<\/span><\/span>. (F&#xFC;r genaue Daten &#xFC;ber das <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Suchvolumen<\/span><\/span> bestimmter Keywords solltest du jedoch den Google <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Keyword<\/span><\/span>-Planer verwenden). So kannst du herausfiltern, welche Keywords h&#xE4;ufig gesucht werden und wo tendenziell viele Besucher zu erreichen sind.<\/p>\n\n<h2>Fazit<\/h2>\n<p>Es gibt noch viele weitere M&#xF6;glichkeiten, wie du <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Low Hanging Fruits<\/span><\/span> optimieren kannst. Aber f&#xFC;r den Moment reichen die hier beschriebenen Ma&#xDF;nahmen aus, um die ersten Erfolge zu erzielen. Je nach <span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Keyword<\/span><\/span> wirst du dein Ziel mit einem kleinen Budget erreichen k&#xF6;nnen. Vergiss nicht, deinen Erfolg zu &#xFC;berwachen &#x2013; es gibt zahlreiche Tools, darunter die Google Search Console, die dir dabei helfen. Dann bleibt nur noch zu sagen: Viel Spa&#xDF; beim Obstpfl&#xFC;cken!<\/p>\n<p><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'><span class=\"\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Low Hanging Fruits<\/span><\/span> gibt es auch au&#xDF;erhalb der SEO-Branche. In der Wirtschaft liegt der Schwerpunkt auf dem Kosten-Nutzen-Verh&#xE4;ltnis &#x2013; mit wenig Aufwand &#xFC;berdurchschnittliche Erfolge zu erzielen. Genau darum geht es bei SEO: mit wenig Aufwand die Positionen verbessern!<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":31581,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-15672","glossary","type-glossary","status-publish","has-post-thumbnail","hentry"],"acf":{"show_faq":true,"faq_q_1":"Was sind Low-Hanging Fruits? ","faq_antwort_1":"Low-Hanging Fruits sind Ergebnisse oder Produkte, die mit minimalem Aufwand einfach und schnell erreicht werden k\u00f6nnen. Es geht darum, sich auf einfache Ergebnisse oder Aufgaben zu konzentrieren, um schnelle Erfolge und Ergebnisse zu erzielen. Low-Hanging Fruits sind leicht zu erreichen, erfordern aber normalerweise keine tiefgehenden Investitionen in Ressourcen oder Zeit.","faq_q_2":"Wie nutzt man Low-Hanging Fruits?","faq_antwort_2":"Man nutzt Low-Hanging Fruits, um schnelle Ergebnisse zu erzielen, ohne aufwendige Investitionen oder tiefgehenden Zeitaufwand. Man kann Low-Hanging Fruits auch nutzen, um eine neue Technologie oder Strategie zu testen, ohne sich auf ein umfangreicheres Projekt einzulassen.","faq_q_3":"Warum nutzt man Low-Hanging Fruits?","faq_antwort_3":"Man nutzt Low-Hanging Fruits, um schnelle Ergebnisse zu erzielen, ohne gro\u00dfe Investitionen oder Ressourcen zu ben\u00f6tigen. Es ist eine gute M\u00f6glichkeit, ein Projekt schnell voranzutreiben, ohne dabei zu viel Zeit und Ressourcen zu investieren.","faq_q_4":"Welche Art von Low-Hanging Fruits gibt es?","faq_antwort_4":"Es gibt eine Vielzahl von Low-Hanging Fruits, von denen einige als leicht umzusetzende Ideen oder Aktivit\u00e4ten angesehen werden k\u00f6nnen. Einige Beispiele sind kosteng\u00fcnstige Marketingkampagnen, die Erstellung einer wichtigen Datei oder die Erh\u00f6hung des Kundenstamms.","faq_q_5":"Wo findet man Low-Hanging Fruits?","faq_antwort_5":"Low-Hanging Fruits k\u00f6nnen \u00fcberall gefunden werden. Man sollte sich Zeit nehmen, um nach M\u00f6glichkeiten zu suchen, um eine Aufgabe leicht zu erledigen. Man kann auch die anderen Mitglieder der Organisation um Rat fragen, um zu sehen, ob sie ein besseres Verst\u00e4ndnis f\u00fcr m\u00f6gliche Low-Hanging Fruits haben.","faq_q_6":"Wie w\u00e4hlt man Low-Hanging Fruits aus? ","faq_antwort_6":"Wenn man sich entschieden hat, Low-Hanging Fruits zu nutzen, sollte man sich die Zeit nehmen, um die bestm\u00f6gliche L\u00f6sung zu finden. Um die besten Low-Hanging Fruits auszuw\u00e4hlen, sollte man sich anstrengen, um die Ergebnisse oder Produkte zu identifizieren, die mit geringem Aufwand und schnellen Ergebnissen am einfachsten zu erreichen sind.","faq_q_7":"Kann man Low-Hanging Fruits nutzen, um neue Technologien zu erforschen?","faq_antwort_7":"Ja, man kann Low-Hanging Fruits nutzen, um neue Technologien zu erforschen. Low-Hanging Fruits sind eine ideale M\u00f6glichkeit, neue Technologien zu erforschen, ohne gro\u00dfe Investitionen in Ressourcen oder Zeit. Man kann auch Low-Hanging Fruits nutzen, um neue Strategien oder Techniken zu testen, bevor man sich auf umfangreichere Projekte einl\u00e4sst.","faq_q_8":"Welche Vorteile hat das Nutzen von Low-Hanging Fruits?","faq_antwort_8":"Low-Hanging Fruits bieten viele Vorteile. Zum Beispiel erm\u00f6glichen sie es einem, schnelle Ergebnisse zu erzielen, ohne gro\u00dfe Investitionen in Ressourcen oder Zeit. Sie sind auch eine gute M\u00f6glichkeit, ein Projekt voranzutreiben, ohne dabei zu viel Zeit und Ressourcen zu investieren.","faq_q_9":"K\u00f6nnen Low-Hanging Fruits auch als Motivation fungieren?","faq_antwort_9":"Ja, man kann Low-Hanging Fruits nutzen, um sich selbst und andere zu motivieren. Indem man sich auf einfache Ergebnisse oder Aufgaben konzentriert, k\u00f6nnen schnelle Erfolge und Ergebnisse erzielt werden, was wiederum als Motivation f\u00fcr die weitere Arbeit dienen kann.","faq_q_10":"Gibt es Risiken beim Nutzen von Low-Hanging Fruits?","faq_antwort_10":"Es besteht immer das Risiko, dass Low-Hanging Fruits nicht so effektiv sind, wie man es sich erhofft. Man sollte sich daher bewusst sein, dass man m\u00f6glicherweise nicht die gew\u00fcnschten Ergebnisse erzielt und daher Ressourcen oder Zeit in das Projekt investieren muss."},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>WOLF OF SEO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wolf-of-seo.de\/en\/what-is\/low-hanging-fruits\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Low Hanging Fruits\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wolf-of-seo.de\/en\/what-is\/low-hanging-fruits\/\" \/>\n<meta property=\"og:site_name\" content=\"WOLF OF SEO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wolf.of.seo.ns\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-14T15:24:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Low-Hanging-Fruits.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wolf_of_seo\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/low-hanging-fruits\\\/\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/low-hanging-fruits\\\/\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/low-hanging-fruits\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/low-hanging-fruits\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Low-Hanging-Fruits.jpg\",\"datePublished\":\"2021-12-22T17:44:07+00:00\",\"dateModified\":\"2023-01-14T15:24:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/low-hanging-fruits\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/low-hanging-fruits\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/low-hanging-fruits\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Low-Hanging-Fruits.jpg\",\"contentUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Low-Hanging-Fruits.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/was-ist\\\/low-hanging-fruits\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wolf-of-seo.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Low Hanging Fruits\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#website\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/\",\"name\":\"WOLF OF SEO\",\"description\":\"Die E-Commerce SEO-Agentur\",\"publisher\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wolf-of-seo.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#organization\",\"name\":\"WOLF OF SEO\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo_wos_beitragsbild3.jpg\",\"contentUrl\":\"https:\\\/\\\/wolf-of-seo.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo_wos_beitragsbild3.jpg\",\"width\":1,\"height\":1,\"caption\":\"WOLF OF SEO\"},\"image\":{\"@id\":\"https:\\\/\\\/wolf-of-seo.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wolf.of.seo.ns\",\"https:\\\/\\\/x.com\\\/wolf_of_seo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"WOLF OF SEO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wolf-of-seo.de\/en\/what-is\/low-hanging-fruits\/","og_locale":"en_US","og_type":"article","og_title":"Low Hanging Fruits","og_url":"https:\/\/wolf-of-seo.de\/en\/what-is\/low-hanging-fruits\/","og_site_name":"WOLF OF SEO","article_publisher":"https:\/\/www.facebook.com\/wolf.of.seo.ns","article_modified_time":"2023-01-14T15:24:38+00:00","og_image":[{"url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Low-Hanging-Fruits.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@wolf_of_seo","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wolf-of-seo.de\/was-ist\/low-hanging-fruits\/","url":"https:\/\/wolf-of-seo.de\/was-ist\/low-hanging-fruits\/","name":"","isPartOf":{"@id":"https:\/\/wolf-of-seo.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wolf-of-seo.de\/was-ist\/low-hanging-fruits\/#primaryimage"},"image":{"@id":"https:\/\/wolf-of-seo.de\/was-ist\/low-hanging-fruits\/#primaryimage"},"thumbnailUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Low-Hanging-Fruits.jpg","datePublished":"2021-12-22T17:44:07+00:00","dateModified":"2023-01-14T15:24:38+00:00","breadcrumb":{"@id":"https:\/\/wolf-of-seo.de\/was-ist\/low-hanging-fruits\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wolf-of-seo.de\/was-ist\/low-hanging-fruits\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wolf-of-seo.de\/was-ist\/low-hanging-fruits\/#primaryimage","url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Low-Hanging-Fruits.jpg","contentUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2023\/01\/Low-Hanging-Fruits.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/wolf-of-seo.de\/was-ist\/low-hanging-fruits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wolf-of-seo.de\/"},{"@type":"ListItem","position":2,"name":"Low Hanging Fruits"}]},{"@type":"WebSite","@id":"https:\/\/wolf-of-seo.de\/#website","url":"https:\/\/wolf-of-seo.de\/","name":"WOLF OF SEO","description":"The e-commerce SEO agency","publisher":{"@id":"https:\/\/wolf-of-seo.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wolf-of-seo.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wolf-of-seo.de\/#organization","name":"WOLF OF SEO","url":"https:\/\/wolf-of-seo.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wolf-of-seo.de\/#\/schema\/logo\/image\/","url":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2021\/11\/logo_wos_beitragsbild3.jpg","contentUrl":"https:\/\/wolf-of-seo.de\/wp-content\/uploads\/2021\/11\/logo_wos_beitragsbild3.jpg","width":1,"height":1,"caption":"WOLF OF SEO"},"image":{"@id":"https:\/\/wolf-of-seo.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wolf.of.seo.ns","https:\/\/x.com\/wolf_of_seo"]}]}},"_links":{"self":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/glossary\/15672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/glossary\/15672\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/media\/31581"}],"wp:attachment":[{"href":"https:\/\/wolf-of-seo.de\/en\/wp-json\/wp\/v2\/media?parent=15672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}